{"id":3920,"date":"2024-05-21T17:31:39","date_gmt":"2024-05-21T15:31:39","guid":{"rendered":"https:\/\/stage.usercentrics.com\/es\/?page_id=23880"},"modified":"2024-09-11T10:17:58","modified_gmt":"2024-09-11T08:17:58","slug":"privacy-policy-until-may-2024","status":"publish","type":"page","link":"https:\/\/usercentrics.com\/es\/privacy-policy-until-may-2024\/","title":{"rendered":"Privacy Policy until 15 may 2024"},"content":{"rendered":"<div class=\"uc-flex-row\" style=\"--padding-top: 0px; --padding-bottom: var(--wp--preset--spacing--5-xl);\"><div class=\"uc-flex-column\" style=\"--column-size: var(--column-size-12);--i:1;\">\n    \n<script>\n  window.UC_UI_SUPPRESS_CMP_DISPLAY = true;\n<\/script>\n\n\n\n\n\n\n\n<h1 class=\"wp-block-heading\">Pol\u00edtica de privacidad v\u00e1lida hasta 15 de mayo de 2024<\/h1>\n\n\n\n\n\n\n\n\n<p>www.usercentrics.com<\/p>\n<p><span style=\"font-weight: 400;\">\u00daltima actualizaci\u00f3n<\/span>: <span style=\"font-weight: 400;\">22 de marzo de 2024<\/span><\/p>\n\n\n\n<p>Su privacidad es importante para nosotros. Esta Pol\u00edtica de privacidad cubre lo que recopilamos y c\u00f3mo usamos, divulgamos, transferimos y almacenamos su informaci\u00f3n.<\/p>\n\n\n\n\n\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-1\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-1-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-1-content\">\n        I. Nombre de la persona responsable    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-1-content\"\n         aria-labelledby=\"uc-accordion-item-1-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <p>La persona responsable en el marco del RGPD y otras leyes nacionales de protecci\u00f3n de datos de los Estados miembros, as\u00ed como de otros reglamentos de protecci\u00f3n de datos es:<\/p>\n<p>Usercentrics GmbH<br \/>\nSendlinger Stra\u00dfe 7<br \/>\n<span style=\"font-weight: 400;\">80331 M\u00fanich<\/span><br \/>\n<span style=\"font-weight: 400;\">Alemania<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Correo electr\u00f3nico<\/span>: <a href=\"mailto:datenschutz@usercentrics.com\">datenschutz@usercentrics.com<\/a> | <span style=\"font-weight: 400;\">Sitio web:<\/span>\u00a0www.usercentrics.com<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-2\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-2-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-2-content\">\n        II. DELEGADO DE PROTECCI\u00d3N DE DATOS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-2-content\"\n         aria-labelledby=\"uc-accordion-item-2-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <p>Puede ponerse en contacto con nuestro delegado de protecci\u00f3n de datos mediante:<\/p>\n<p><strong>SECUWING GmbH &#038; Co. KG<\/strong><br \/>\nMaximilian Hartung<br \/>\nFrauentorstr. 9<br \/>\n86152 <span style=\"font-weight: 400;\">Augsburgo<\/span><br \/>\n<span style=\"font-weight: 400;\">Alemania<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Correo electr\u00f3nico: <\/span><a class=\"ProsemirrorEditor-link\" href=\"mailto:epost@datenschutz-agentur.de\">epost@datenschutz-agentur.de<\/a> | <span style=\"font-weight: 400;\">Tel\u00e9fono: <\/span>+49 821 90786450 | Fax: +49 821 90786459<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-3\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-3-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-3-content\">\n        III. INFORMACI\u00d3N GENERAL SOBRE LA RECOPILACI\u00d3N Y EL TRATAMIENTO DE SUS DATOS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-3-content\"\n         aria-labelledby=\"uc-accordion-item-3-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <h3><b>1. Alcance del tratamiento<\/b><\/h3>\n<p>En principio, tratamos los datos personales s\u00f3lo en la medida en que sea necesario para ofrecer un sitio web operativo y nuestros contenidos y servicios. Tratamos los datos personales de nuestros usuarios, exclusivamente con su consentimiento, de forma regular. Se aplica una excepci\u00f3n en los casos en los que no se puede obtener el consentimiento previo por motivos de hecho y el tratamiento de los datos est\u00e1 permitido por la ley.<\/p>\n<h3>2. Base jur\u00eddica<\/h3>\n<p>En la medida en que obtengamos el consentimiento del interesado para el tratamiento de los datos personales, el Art. 6 p\u00e1rr. 1 apdo. a del RGPD sirve como base jur\u00eddica.<\/p>\n<p>Si el tratamiento de los datos personales es necesario para la ejecuci\u00f3n de un contrato en el que el interesado es una parte, el Art. 6 p\u00e1rr. 1 apdo. b del RGPD es la base jur\u00eddica. Esto tambi\u00e9n se aplica a las operaciones de tratamiento necesarias para desempe\u00f1ar acciones precontractuales.<\/p>\n<p>En la medida en que el tratamiento de datos personales sea necesario para cumplir con una obligaci\u00f3n legal aplicable a nuestra empresa, el Art. 6 p\u00e1rr. 1 apdo. c del RGPD sirve como base jur\u00eddica.<\/p>\n<p>Si el tratamiento es necesario para satisfacer los intereses leg\u00edtimos de nuestra empresa o de un tercero, y si los intereses, derechos fundamentales y libertades del interesado no prevalecen sobre el primer inter\u00e9s, el Art. 6 p\u00e1rr. 1 apdo. f del RGPD sirve como base jur\u00eddica para el tratamiento.<\/p>\n<h3>3. Almacenamiento y eliminaci\u00f3n de sus datos<\/h3>\n<p>En principio, s\u00f3lo almacenamos sus datos por el tiempo necesario para cumplir con las obligaciones contractuales o legales para las cuales han sido recopilados. Despu\u00e9s de eso, eliminamos los datos inmediatamente, salvo que todav\u00eda necesitemos los datos hasta la expiraci\u00f3n del periodo de limitaciones estatutarias para su uso como evidencia en caso de denuncias bajo la legislaci\u00f3n civil o debido a obligaciones de retenci\u00f3n estatutarias.<\/p>\n<p>Para prop\u00f3sitos probatorios, debemos retener los datos contractuales por seis a\u00f1os desde el fin del a\u00f1o de finalizaci\u00f3n de la relaci\u00f3n comercial con usted. Cualquier reclamaci\u00f3n prescribe en ese momento, como pronto, de acuerdo con el periodo de limitaci\u00f3n estatutaria.<\/p>\n<p>Incluso despu\u00e9s de esto, todav\u00eda debemos almacenar algunos de sus datos por razones de contabilidad. Estamos obligados a hacerlo por las obligaciones de documentaci\u00f3n legal que pueden surgir de la Ley Comercial de Alemania (Handelsgesetzbuch), la Ley Fiscal de Alemania (Abgabenordnung), la Ley Bancaria de Alemania (Kreditwesengesetz, KWG), La Ley de Blanqueamiento de Capital de Alemania (Geldw\u00e4schegesetz, GWG) y la Ley de Comercio de Valores de Alemania (Wertpapierhandelsgesetz, WpHG). Los periodos de retenci\u00f3n de documentos especificados son de dos a diez a\u00f1os.<\/p>\n<p>Eliminamos o bloqueamos la informaci\u00f3n personal del sujeto tan pronto como el prop\u00f3sito de almacenamiento se cumple. Tambi\u00e9n se puede almacenar si est\u00e1 previsto por el legislador europeo o nacional en las regulaciones de la UE, leyes o regulaciones a las que nuestra empresa est\u00e1 sujeta. El bloqueo o eliminaci\u00f3n de los datos tambi\u00e9n se da cuando un periodo de almacenamiento prescribe seg\u00fan los est\u00e1ndares mencionados, salvo que haya una necesidad de almacenamiento posterior para la conclusi\u00f3n de un contrato o el cumplimiento del contrato.<\/p>\n<h3>4. Importante<\/h3>\n<p>Sus datos de consentimiento se tratar\u00e1n para el uso de este sitio web y el uso del la plataforma de gesti\u00f3n de consentimiento implementada. Utilizamos la plataforma Google Cloud provista por Google EMEA Ltd.. Los servidores est\u00e1n ubicados en Alemania y B\u00e9lgica. Nos gustar\u00eda informarle que no podemos excluir el hecho de que los datos pueden transferirse a EE. UU. y pueden estar sujetos al acceso de las autoridades de seguridad de EE. UU. de conformidad con el T\u00edtulo 50 p\u00e1rr. 1881(b)(4) del C\u00f3digo de los Estados Unidos y el T\u00edtulo 50 p\u00e1rr. 1881a (=FISA 702) del C\u00f3digo de los Estados Unidos. En caso de que sus datos se transfieran a los EE. UU. u otro tercer pa\u00eds, hemos tomado las medidas necesarias con Google de acuerdo con el Art. 44 y siguientes del RGPD. Puede encontrar m\u00e1s informaci\u00f3n en las referencias de protecci\u00f3n de datos de Google. Adicionalmente, hemos tomado medidas de protecci\u00f3n extra para garantizar la seguridad de los datos.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-4\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-4-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-4-content\">\n        IV. DISPOSICIONES DEL SITIO WEB Y CREACI\u00d3N DE ARCHIVOS DE REGISTRO    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-4-content\"\n         aria-labelledby=\"uc-accordion-item-4-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <h3>1. Alcance del tratamiento de datos<\/h3>\n<p>Cada vez que se accede a nuestro sitio web, nuestro sistema recopila autom\u00e1ticamente datos e informaci\u00f3n del sistema inform\u00e1tico del ordenador que realiza la comunicaci\u00f3n. Puede tratarse de informaci\u00f3n como la siguiente:<\/p>\n<ul>\n<li>Informaci\u00f3n sobre el tipo y la versi\u00f3n de su navegador de Internet<\/li>\n<li>El sistema operativo de su ordenador o tel\u00e9fono inteligente<\/li>\n<li>Su proveedor de servicios de Internet<\/li>\n<li>Su direcci\u00f3n IP<\/li>\n<li>Fecha y hora del acceso<\/li>\n<li>Localizaci\u00f3n geogr\u00e1fica<\/li>\n<li>Sitios web desde los que ha llegado<\/li>\n<li>Sitios web que visita desde nuestro sitio web.<\/li>\n<li>Cuando aplique &#8211; URL de referencia del sitio web del Socio<\/li>\n<\/ul>\n<p>Recopilamos dicha informaci\u00f3n en los llamados \u00abarchivos de registro\u00bb, para que se pueda mostrar nuestro sitio web de forma correcta y podamos identificar las causas de cualquier problema t\u00e9cnico, para la optimizaci\u00f3n t\u00e9cnica de nuestros sitios web y para proteger los sistemas y redes de nuestro ordenador. Para tales fines, la base jur\u00eddica es el inter\u00e9s leg\u00edtimo en el tratamiento de los datos seg\u00fan el Art. 6 p\u00e1rr. 1 apdo. f del RGPD.<\/p>\n<p>Los datos se eliminar\u00e1n tan pronto como no sean necesarios para los fines para los que fueron recopilados. Por lo general, esta informaci\u00f3n t\u00e9cnica se borrar\u00e1 o se har\u00e1 irreconocible a m\u00e1s tardar despu\u00e9s de siete d\u00edas.<\/p>\n<p>La recopilaci\u00f3n de datos para la disposici\u00f3n del sitio web y el almacenamiento de los datos en archivos de registro es esencial para el funcionamiento del sitio web.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-5\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-5-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-5-content\">\n        V. SOLICITUDES DE CONTACTO PARA RECIBIR INFORMACI\u00d3N SOBRE EL PRODUCTO, UNA DEMOSTRACI\u00d3N O CUALQUIER OTRO TIPO DE CONSULTA    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-5-content\"\n         aria-labelledby=\"uc-accordion-item-5-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <h3>1. Descripci\u00f3n y alcance del tratamiento de datos<\/h3>\n<p>En nuestro sitio web puede ponerse en contacto con nosotros a trav\u00e9s de varias opciones: p. ej., reservar una demostraci\u00f3n, solicitar un presupuesto, pedir informaci\u00f3n sobre el producto, solicitar gu\u00edas, enviar el formulario de contacto, tickets de soporte. Si usa estas opciones, los datos introducidos en la m\u00e1scara de entrada se nos transmitir\u00e1n y guardar\u00e1n. Adem\u00e1s de los datos macro espec\u00edficos de entrada, se recopilan y almacenan la direcci\u00f3n IP y la fecha y hora de la solicitud.<\/p>\n<p>Alternativamente, puede contactar con nosotros por correo electr\u00f3nico. En ese caso, se almacenar\u00e1n sus datos personales transmitidos por correo electr\u00f3nico.<\/p>\n<p>En este contexto, no se ceder\u00e1n los datos a terceros, a menos que sea necesario para el procesamiento de la consulta (por ejemplo, la herramienta para reservar una demostraci\u00f3n). En cualquier caso, los datos se utilizar\u00e1n exclusivamente para el tratamiento de la conversaci\u00f3n, salvo que se acuerde de otra manera.<\/p>\n<h3>2. Base jur\u00eddica del tratamiento<\/h3>\n<p>La base jur\u00eddica para el tratamiento de los datos en presencia del consentimiento general del usuario es el Art. 6 p\u00e1rr. 1 apdo. a del RGPD.<\/p>\n<h3>3. Finalidad del tratamiento de datos<\/h3>\n<p>El tratamiento de los datos personales de la m\u00e1scara de entrada se efect\u00faa \u00fanicamente para procesar su solicitud. En caso de que contacte v\u00eda correo electr\u00f3nico, esto tambi\u00e9n incluye el inter\u00e9s leg\u00edtimo requerido en el tratamiento de los datos.<\/p>\n<p>Los dem\u00e1s datos personales procesados durante el proceso de env\u00edo sirven para evitar un uso indebido del formulario de contacto y para garantizar la seguridad de nuestros sistemas de tecnolog\u00eda de la informaci\u00f3n.<\/p>\n<h3>4. Duraci\u00f3n del almacenamiento<\/h3>\n<p>Si ha reservado una demostraci\u00f3n, ha solicitado informaci\u00f3n del producto o de una oferta, nos reservamos el derecho de almacenar los datos durante dos a\u00f1os para medir la rentabilidad de nuestras ventas y marketing. De lo contrario, eliminaremos los datos tan pronto como ya no sean necesarios para cumplir el prop\u00f3sito para el que se recopilaron. Para los datos personales introducidos en el formulario de contacto y aquellos enviados por correo electr\u00f3nico, se hace cuando finaliza la conversaci\u00f3n con usted. La conversaci\u00f3n se da por finalizada cuando las circunstancias dejan claro que los hechos relevantes se han aclarado.<\/p>\n<h3>5. Revocar el consentimiento y posibilidad de eliminaci\u00f3n<\/h3>\n<p>Tiene la posibilidad de revocar su consentimiento para el tratamiento de los datos personales en cualquier momento. Si se pone en contacto con nosotros por correo electr\u00f3nico, puede oponerse al almacenamiento de sus datos personales en cualquier momento. En tal caso, la conversaci\u00f3n no puede continuar y se eliminar\u00e1n todos los datos personales almacenados en el transcurso del contacto.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-6\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-6-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-6-content\">\n        VI. NEWSLETTER, RECOMENDACIONES DE PRODUCTO, WEBINARS Y ENCUESTAS DE CLIENTES    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-6-content\"\n         aria-labelledby=\"uc-accordion-item-6-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <h3>1. Newsletter<\/h3>\n<p>Al darse de alta para el newsletter, los datos introducidos en la capa de entrada tambi\u00e9n ser\u00e1n almacenados, con el fin de proveer el newsletter. La base jur\u00eddica de este tratamiento es el art. 6 p\u00e1rr. 1 apdo. a del RGPD. Su direcci\u00f3n de correo electr\u00f3nico, tiempo de suscripci\u00f3n y la direcci\u00f3n IP usada para suscribirse se retendr\u00e1n por el tiempo en que se suscriba a nuestro newsletter. Este servicio est\u00e1 prove\u00eddo mediante doble opt-in. De este modo, recibir\u00e1 un correo electr\u00f3nico con un link mediante el cual podr\u00e1 confirmar que usted es propietario de la direcci\u00f3n de correo electr\u00f3nico y que quiere ser notificado mediante nuestro servicio de correo electr\u00f3nico. Puede darse de baja de este servicio empleando el link prove\u00eddo en cada newsletter en cualquier momento.<\/p>\n<h3>2. Recomendaciones de Producto<\/h3>\n<p>Ser\u00e1 informado por Usercentrics de cambios relevantes en relaci\u00f3n al Servicio, tales como la implementaci\u00f3n de funciones adicionales, por correo electr\u00f3nico, si contrata el producto de Usercentrics. La base jur\u00eddica para esto es el Art. 6 p\u00e1rr. 1 apdo. f del RGPD en conjunci\u00f3n con el \u00a7 7 p\u00e1rr. 3 de la UWG alemana.<\/p>\n<h3>3. Webinars<\/h3>\n<p>Usercentrics ofrece webinars de forma puntual, a los que puede inscribirse desde nuestro sitio web. En estos casos, los datos introducidos en el formulario de inscripci\u00f3n durante el proceso de inscripci\u00f3n ser\u00e1n usados por Usercentrics con el prop\u00f3sito de llevar a cabo el webinar y comunicaciones relacionadas con el webinar y otros temas relevantes. Si el webinar se organiza de forma conjunta con un socio, los datos podr\u00edan ser compartidos tambi\u00e9n con ellos. Los datos se tratan bajo la base jur\u00eddica del consentimiento, Art. 6 par\u00e1grafo 1 s. 1 apdo a del RGPD. Tiene el derecho a rechazar el consentimiento al tratamiento de dichos datos en cualquier momento poni\u00e9ndose en contacto con nosotros a trav\u00e9s de <a href=\"mailto:unsubscribe@usercentrics.com\">unsubscribe@usercentrics.com<\/a>.<\/p>\n<h3>3. Encuestas de Clientes<\/h3>\n<p>Si contrata un producto con nosotros, tambi\u00e9n usaremos su direcci\u00f3n de correo electr\u00f3nico para enviarle encuestas de clientes y de satisfacci\u00f3n. Usaremos los resultados para mejorar nuestros productos y servicios. La base jur\u00eddica para esto es el Art. 6 p\u00e1rr. 1 apdo. a del RGPD, si ha dado su consentimiento. En algunos casos, el Art. 6 p\u00e1rr. 1 apdo. f del RGPD puede ser de aplicaci\u00f3n, justificado por nuestro inter\u00e9s leg\u00edtimo de mejorar constantemente nuestro servicio.<\/p>\n<h3>4. Plataforma de gesti\u00f3n de preferencias<\/h3>\n<p>Utilizamos la Plataforma de Gesti\u00f3n de Preferencias de Usercentrics para ofrecerle, como destinatario de nuestro newsletter y otros tipos de comunicaci\u00f3n, la opci\u00f3n de elegir qu\u00e9 tipos de comunicaci\u00f3n desea recibir. Puede cambiar su configuraci\u00f3n y preferencias en cualquier momento. El uso de este servicio implica el almacenamiento de su direcci\u00f3n de correo electr\u00f3nico y de la decisi\u00f3n sobre sus preferencias. Utilizamos estos datos para poder enviarle comunicaciones basadas en sus preferencias. Los datos mencionados s\u00f3lo se procesan con su consentimiento (Art. 6 p\u00e1rr. 1(1) apdo. a del RGPD). Puede retirar su consentimiento en cualquier momento. Los datos no se comparten con terceros.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-7\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-7-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-7-content\">\n        VII. SE CONVIERTE EN CLIENTE O SOCIO DE USERCENTRICS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-7-content\"\n         aria-labelledby=\"uc-accordion-item-7-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <h3>1. Descripci\u00f3n y alcance del tratamiento de datos<\/h3>\n<p>Puede convertirse en cliente o socios de Usercentrics. Los siguientes datos se recopilan durante el proceso de registro:<\/p>\n<ul>\n<li>Su direcci\u00f3n de correo electr\u00f3nico,<\/li>\n<li>nombre y apellido(s),<\/li>\n<li>si fuera necesario, la afiliaci\u00f3n a la empresa,<\/li>\n<li>informaci\u00f3n de pago (posiblemente la empresa),<\/li>\n<li>otros datos que le solicitamos y<\/li>\n<li>posiblemente datos que recibamos durante la relaci\u00f3n comercial.<\/li>\n<\/ul>\n<h3>2. Base jur\u00eddica del tratamiento<\/h3>\n<p>La base jur\u00eddica para el tratamiento de los datos en presencia del consentimiento del usuario es el art. 6 p\u00e1rr. 1 apdo. a del RGPD y el art. 6 p\u00e1rr. 1 apdo. b del RGPD, desde el registro del cumplimiento de un contrato o la implementaci\u00f3n de medidas precontractuales.<\/p>\n<h3>3. Finalidad del tratamiento de datos<\/h3>\n<p>El registro es necesario para cumplir con el contrato del cliente o socio o para tomar medidas precontractuales.<\/p>\n<h3>4. Posibilidad de oposici\u00f3n y eliminaci\u00f3n<\/h3>\n<p>Como cliente, siempre tiene la opci\u00f3n de cancelar su cuenta. Puede modificar los datos almacenados sobre usted en cualquier momento. Si los datos son necesarios para cumplir un contrato o para llevar a cabo medidas precontractuales, solo es posible una eliminaci\u00f3n prematura de los datos, a menos que las obligaciones contractuales o legales impidan su eliminaci\u00f3n.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-8\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-8-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-8-content\">\n        VIII. COOKIES Y TECNOLOG\u00cdAS DE SEGUIMIENTO    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-8-content\"\n         aria-labelledby=\"uc-accordion-item-8-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <h3>1. \u00bfQu\u00e9 son las Cookies?<\/h3>\n<p>Cookies del navegador web: Una cookie de navegador web es un peque\u00f1o archivo de texto que un sitio web env\u00eda a su ordenador o dispositivo m\u00f3vil y que su navegador web almacena. Las cookies de navegador web pueden almacenar informaci\u00f3n como su direcci\u00f3n IP u otros identificadores, su tipo de navegador e informaci\u00f3n sobre el contenido que muestra y con el que interact\u00faa en los servicios digitales. Al almacenar dicha informaci\u00f3n, las cookies de navegador web pueden almacenar sus preferencias y ajustes para los servicios en l\u00ednea y analizar c\u00f3mo utiliza dichos servicios.<\/p>\n<p>Tecnolog\u00edas de seguimiento: balizas web, p\u00edxeles, etiqueta, script<\/p>\n<p>Los correos electr\u00f3nicos y aplicaciones m\u00f3viles pueden contener peque\u00f1os archivos de imagen transparentes o l\u00edneas de c\u00f3digo para registrar c\u00f3mo interact\u00faa con ellos. Esta informaci\u00f3n se utiliza para ayudar a los editores de sitios web y aplicaciones a analizar mejor sus servicios y mejorarlos.<\/p>\n<h3>2. Uso, base jur\u00eddica y finalidad<\/h3>\n<p>Utilizamos cookies para que nuestro sitio web sea m\u00e1s f\u00e1cil de usar. Algunos elementos de nuestro sitio web requieren identificar el navegador que realiza la llamada, incluso despu\u00e9s de un salto de p\u00e1gina. Tanto las cookies como el almacenamiento de datos en el almacenamiento local, solo permiten funcionalidades que deber\u00eda contribuir a una mejor experiencia de usuario en nuestro sitio web. No usamos cookies con datos personales sin que se haya dado consentimiento.<\/p>\n<p>Adicionalmente, usamos cookies en nuestro sitio web que permiten un an\u00e1lisis del comportamiento de navegaci\u00f3n de los usuarios.<\/p>\n<p>Cuando accede a nuestro sitio web, el usuario es informado sobre el uso de cookies para fines anal\u00edticos y su consentimiento al procesamiento de los datos personales usado en este contexto es obtenido.<\/p>\n<p>La base jur\u00eddica para el el tratamiento de datos personales usando cookies t\u00e9cnicamente necesarias el art\u00edculo 6 p\u00e1rr. 1 apdo. f del RGPD. El prop\u00f3sito de usar cookies t\u00e9cnicamente necesarias es facilitar el uso de los sitios web para los usuarios. Algunas caracter\u00edsticas de nuestro sitio web no pueden ser ofrecidas sin el uso de cookies. Para estas, es necesario que el navegador sea reconocido incluso despu\u00e9s de un salto de p\u00e1gina. Necesitamos de cookies para las siguientes aplicaciones: aceptaci\u00f3n de ajustes de idioma. Los datos del usuario recopilados mediante cookies t\u00e9cnicamente necesarias no ser\u00e1n empleados para crear perfiles de usuario.<\/p>\n<p>La base jur\u00eddica para el procesamiento de datos personales para fines anal\u00edticos es el consentimiento del usuario, Art. 6 p\u00e1rr. 1 apdo. a del RGPD. El uso de las cookies anal\u00edticas es para mejorar la calidad de nuestro sitio web y sus contenidos. Mediante las cookies anal\u00edticas, aprendemos c\u00f3mo el sitio web se usa y as\u00ed podemos optimizar constantemente nuestra oferta.<\/p>\n<h3>3. Duraci\u00f3n del almacenamiento y las opciones de objeci\u00f3n y eliminaci\u00f3n<\/h3>\n<p>Las cookies se almacenan en el ordenador del usuario y nos son transmitidas. Por lo tanto, usted, como usuario, tiene pleno control del uso de sus cookies. Al cambiar la configuraci\u00f3n de su navegador de Internet, puede deshabilitar o restringir la transmisi\u00f3n de cookies. Las cookies ya guardadas pueden eliminarse en cualquier momento. Esto tambi\u00e9n se puede hacer de forma autom\u00e1tica. Si las cookies est\u00e1n deshabilitadas para nuestro sitio web, es posible que no se puedan utilizar todas las funciones del sitio web en toda su extensi\u00f3n.<\/p>\n<h3>4. Receptores de los datos<\/h3>\n<p>S\u00f3lo transmitimos los datos que hemos recopilado si esto es necesario para el cumplimiento de un contrato o para la provisi\u00f3n de la funcionalidad t\u00e9cnica del sitio web, o si hay alguna otra base jur\u00eddica para transmitir la informaci\u00f3n.<\/p>\n<p>En principio, tratamos los datos nosotros mismos. En algunos casos, sin embargo, tambi\u00e9n usamos proveedores de servicios. Adem\u00e1s de los procesadores mencionados en esta pol\u00edtica de privacidad, estos pueden incluir, en particular, centros de datos que almacenan nuestro sitio web y bases de datos, proveedores de servicios de TI que mantienen nuestros sistemas, y consultor\u00edas. Si transmitimos datos a procesadores, s\u00f3lo pueden usar los datos para cumplir sus tareas. Los procesadores han sido cuidadosamente seleccionados y contratados por nosotros. Est\u00e1n contractualmente obligados a nuestras instrucciones, tienen aplicadas medidas t\u00e9cnicas y organizativas adecuadas para proteger los derechos de los sujetos de datos y est\u00e1n continuamente monitorizados por nosotros.<\/p>\n<p>Adicionalmente, podr\u00edan haber revelaciones vinculadas a solicitudes oficiales, \u00f3rdenes judiciales y procedimientos legales si son necesarias para investigaciones legales o aplicaciones de la legislaci\u00f3n. Cuando los Gobiernos hacen peticiones de datos de usuarios acordes a la Ley a Usercentrics, Usercentrics vela por limitar la divulgaci\u00f3n. Usercentrics s\u00f3lo revela los datos espec\u00edficamente demandados por la petici\u00f3n legal.<\/p>\n<p>Si nos vemos obligados a revelar sus datos, Usercentrics le notificar\u00e1 sin demora y le proveer\u00e1 una copia de la petici\u00f3n salvo que nos est\u00e9 legalmente prohibido.<\/p>\n<p>Si Usercentrics contrata a terceras partes para la recopilaci\u00f3n, tratamiento y uso de los datos dentro del alcance del tratamiento contratado de acuerdo con el Art. 28 del RGPD, \u00e9stos tambi\u00e9n tendr\u00e1n lugar exclusivamente en cumplimiento con las disposiciones estatutarias en protecci\u00f3n de datos.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-9\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-9-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-9-content\">\n        IX. TECNOLOG\u00cdAS IMPLEMENTADAS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-9-content\"\n         aria-labelledby=\"uc-accordion-item-9-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <h3>1. Tecnolog\u00edas de Terceros usadas en el sitio web<\/h3>\n<div class=\"uc-embed\" uc-layout=\"1\" uc-embed-type=\"all\"\n                                                                       uc-embed-show-toggle=\"true\"><\/div>\n<ul>\n<li><strong>Zapier<\/strong><\/li>\n<\/ul>\n<p>Utilizamos el servicio Zapier como software de automatizaci\u00f3n del flujo de trabajo. El servicio es proporcionado por Zapier Inc., 548 Market St., # 62411, San Francisco, California 94104, Estados Unidos. Este servicio se utiliza para transferir la informaci\u00f3n introducida en los formularios de nuestro sitio web a nuestros sistemas. Por otra parte, a trav\u00e9s del servicio podr\u00eda tratarse informaci\u00f3n como la direcci\u00f3n IP. La base legal para el uso de este servicio es el inter\u00e9s leg\u00edtimo, art\u00edculo 6 p\u00e1rr. 1 apdo. f del RGPD, en la medida en que el servicio est\u00e1 obligado a transferir la informaci\u00f3n a nuestros sistemas internos. Los datos se suprimir\u00e1n en cuanto dejen de ser necesarios para alcanzar el objetivo que determin\u00f3 su recopilaci\u00f3n. Este servicio podr\u00e1 transferir datos fuera de la UE o del EEE. A tal efecto, hemos firmado cl\u00e1usulas contractuales est\u00e1ndar con el proveedor de servicios.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo Zapier trata los datos, puede consultar la <a href=\"https:\/\/zapier.com\/privacy\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidad<\/a> de Zapier o ponerse en contacto con Zapier en <a href=\"mailto:privacy@zapier.com\">privacy@zapier.com<\/a>.<\/p>\n<ol>\n<li><strong>Leads de LinkedIn<\/strong><\/li>\n<\/ol>\n<p>Utilizamos el servicio proporcionado por LinkedIn Leads para la generaci\u00f3n de oportunidades de clientes o socios. Al inscribirse en los eventos o contenidos de Usercentrics en LinkedIn, trataremos sus datos. La direcci\u00f3n de correo electr\u00f3nico se utilizar\u00e1 para el env\u00edo de los recursos, as\u00ed como para la publicidad directa y la iniciaci\u00f3n de contactos en el contexto de los productos y servicios que ofrecemos. Los datos tambi\u00e9n se comparten con Google Ads con fines de retargeting. La recopilaci\u00f3n de los datos no tiene lugar en el sitio web de Usercentrics, sino en los formularios de registro en LinkedIn. La base legal es el consentimiento, art\u00edculo 6 p\u00e1rr. 1 apdo. f del RGPD. Podr\u00e1 revocar su consentimiento en cualquier momento.<\/p>\n<ol>\n<li><strong>Personio<\/strong><\/li>\n<\/ol>\n<p>Utilizamos el servicio Personio como software de gesti\u00f3n de candidatos. El servicio es proporcionado por Personio GmbH, Rundfunkplatz 4, 80335 M\u00fanich, Alemania. La base legal es el consentimiento, art\u00edculo 6 p\u00e1rr. 1 apdo. f del RGPD. Podr\u00e1 revocar su consentimiento en cualquier momento. Los datos se conservar\u00e1n durante un periodo de 60 d\u00edas una vez concluido el proceso de solicitud. Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo Personio trata los datos, puede consultar la <a href=\"https:\/\/www.personio.es\/proteccion-de-datos\/\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidad<\/a> de Personio o ponerse en contacto con Personio en privacy@personio.com.<\/p>\n<ol>\n<li><strong>Zoom<\/strong><\/li>\n<\/ol>\n<p>Utilizamos el servicio proporcionado por Zoom como servicio de videoconferencia. El servicio es proporcionado por Zoom Video Communications Inc., 55 Almaden Boulevard, 6th Floor, San Jos\u00e9, CA 95113, Estados Unidos. El servicio se utiliza como servicio de videoconferencia para organizar seminarios web y otros tipos de videoconferencias. La base legal es el consentimiento, art\u00edculo 6 p\u00e1rr. 1 apdo. f del RGPD. Podr\u00e1 revocar su consentimiento en cualquier momento. Este servicio podr\u00e1 transferir datos fuera de la UE o del EEE. A tal efecto, hemos firmado cl\u00e1usulas contractuales est\u00e1ndar con el proveedor de servicios y dicho proveedor est\u00e1 incluido en <a href=\"https:\/\/www.dataprivacyframework.gov\/list\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">la Lista marco de privacidad de datos<\/a>.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo Zoom trata los datos, puede consultar la <a href=\"https:\/\/explore.zoom.us\/es\/privacy\/\">pol\u00edtica de privacidad<\/a> de Zoom o ponerse en contacto con Zoom en privacy@zoom.us.<\/p>\n<ol>\n<li><strong>Stripe<\/strong><\/li>\n<\/ol>\n<p>Utilizamos el servicio proporcionado por Stripe como sistema de pago en l\u00ednea. El servicio es proporcionado por Stripe, Inc., 3180 18th Street, San Francisco, CA 94110, Estados Unidos. El servicio se utiliza para habilitar el proceso de pago en el sitio web. La base legal es la ejecuci\u00f3n de un contrato, art\u00edculo 6 p\u00e1rr. 1 apdo. f del RGPD, en la medida en que este servicio es necesario para poder finalizar el proceso de compra. Al utilizar este servicio podr\u00edan tratarse datos como la informaci\u00f3n de pago (incluida la informaci\u00f3n de la tarjeta de pago), la informaci\u00f3n de compra, as\u00ed como la direcci\u00f3n IP. Este servicio podr\u00e1 transferir datos fuera de la UE o del EEE. A tal efecto, hemos firmado cl\u00e1usulas contractuales est\u00e1ndar con el proveedor de servicios y dicho proveedor est\u00e1 incluido en <a href=\"https:\/\/www.dataprivacyframework.gov\/list\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">la Lista marco de privacidad de datos<\/a>.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo Stripe trata los datos, puede consultar la <a href=\"https:\/\/stripe.com\/es\/privacy\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidad<\/a> de Stripe o ponerse en contacto con Stripe en <a href=\"mailto:privacy@stripe.com\">privacy@stripe.com<\/a>.<\/p>\n<ul>\n<li><strong>Demodesk<\/strong><\/li>\n<\/ul>\n<p>Utilizamos el servicio proporcionado por Demodesk como plataforma de reservas y reuniones, con el fin de ofrecer a nuestros usuarios la posibilidad de programar reuniones con nuestros equipos, as\u00ed como para realizar videoconferencias. El servicio es proporcionado por Demodesk GmbH, Isartorplatz 8, 80331 M\u00fanich, Alemania. La base legal es el consentimiento, art\u00edculo 6 p\u00e1rr. 1 apdo. f del RGPD. Podr\u00e1 revocar su consentimiento en cualquier momento. Al utilizar este servicio pueden tratarse datos como el nombre y apellidos, informaci\u00f3n de contacto, datos t\u00e9cnicos (URL de la sesi\u00f3n, resoluci\u00f3n de pantalla, nombres de los participantes, direcciones de correo electr\u00f3nico), transmisi\u00f3n de sonido y v\u00eddeo y direcci\u00f3n IP.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo Demodesk trata los datos, puede consultar la <a href=\"https:\/\/demodesk.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidad<\/a> de Demodesk o ponerse en contacto con Demodesk en <a href=\"mailto:privacy@demodesk.com\">privacy@demodesk.com<\/a>.<\/p>\n<ul>\n<li><strong>Pardot<\/strong><\/li>\n<\/ul>\n<p>Utilizamos el servicio proporcionado por Pardot como software de gesti\u00f3n de relaciones con los clientes, con el fin de gestionar la automatizaci\u00f3n del marketing y la generaci\u00f3n de clientes potenciales. El servicio es proporcionado por Salesforce, Erika-Mann-Stra\u00dfe 31-37, 80636 M\u00fanich, Alemania. La base legal es el consentimiento, art\u00edculo 6 p\u00e1rr. 1 apdo. f del RGPD. Podr\u00e1 revocar su consentimiento en cualquier momento. Al utilizar este servicio, es posible que se procesen datos como el nombre y los apellidos, la informaci\u00f3n de contacto, la direcci\u00f3n de correo electr\u00f3nico, la informaci\u00f3n de la empresa, as\u00ed como la direcci\u00f3n IP.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo Pardot trata los datos, puede consultar la <a href=\"https:\/\/www.salesforce.com\/company\/privacy\">pol\u00edtica de privacidad<\/a> de Pardot o ponerse en contacto con Pardot en <a href=\"mailto:privacy@salesforce.com\">privacy@salesforce.com<\/a>.<\/p>\n<h3>2. Destinatarios de los datos<\/h3>\n<p>Usercentrics no vende, intercambia ni transfiere de otro modo a terceros ninguna informaci\u00f3n personal que permita identificarle.<\/p>\n<p>Lo anterior no incluye a terceros de confianza o encargados del tratamiento que nos ayuden en la operativa de nuestro sitio web, en la realizaci\u00f3n de nuestro negocio o en la prestaci\u00f3n de nuestros servicios. Dichas partes consideradas de confianza pueden tener acceso a informaci\u00f3n personal que le identifique en funci\u00f3n de la necesidad de conocerla y estar\u00e1n obligadas contractualmente a mantener la confidencialidad de la misma.<\/p>\n<p>Tambi\u00e9n compartiremos datos entre las entidades de Usercentrics (Usercentrics A\/S, Usercentrics GmbH, Cybot A\/S [incluyendo CYBOT A\/S, od\u0161t\u011bpn\u00fd z\u00e1vod oficina en Praga]<br \/>\n, Usercentrics Unipessoal, Usercentrics Inc.), lo que incluye en este caso compartir datos entre Cookiebot\u2122 y los productos de Usercentrics cuando sea necesario. Todas las entidades podr\u00e1n tener acceso a la informaci\u00f3n personal que le identifique en funci\u00f3n de la necesidad de conocerla y estar\u00e1n obligadas contractualmente a mantener la confidencialidad de su informaci\u00f3n (acuerdo de controlador conjunto).<\/p>\n<p>Asimismo, podremos divulgar su informaci\u00f3n cuando lo consideremos oportuno en cumplimiento de la ley, para hacer respetar las pol\u00edticas de nuestro sitio o para proteger nuestros derechos o los derechos de terceros, la propiedad o la seguridad. Por otra parte, la informaci\u00f3n de los visitantes que no permita su identificaci\u00f3n personal podr\u00e1 facilitarse a terceros con fines de marketing, publicidad u otros usos.<\/p>\n<p>\u00danicamente divulgaremos los datos que hayamos recopilado si es necesario para el cumplimiento del contrato o para la prestaci\u00f3n de la funcionalidad t\u00e9cnica del sitio web, as\u00ed como si existe otra base legal para la divulgaci\u00f3n de los datos.<\/p>\n<p>En principio, procedemos nosotros mismos al tratamiento de sus datos. En algunos casos, sin embargo, tambi\u00e9n utilizamos proveedores de servicios. Adem\u00e1s de los encargados del tratamiento mencionados en esta pol\u00edtica de privacidad, cabe citar, en particular, los centros de datos que almacenan nuestros sitios web y bases de datos, los proveedores de servicios inform\u00e1ticos que mantienen nuestros sistemas y las empresas de consultor\u00eda. Si transferimos datos a encargados del tratamiento, estos \u00fanicamente podr\u00e1n utilizarlos para llevar a cabo sus funciones. Los encargados del tratamiento han sido cuidadosamente seleccionados y nombrados por nosotros. Est\u00e1n obligados contractualmente por nuestras instrucciones, disponen de medidas t\u00e9cnicas y organizativas adecuadas para proteger los derechos de los interesados y son supervisados regularmente por nuestra parte.<\/p>\n<p>Por otra parte, la divulgaci\u00f3n puede tener lugar en relaci\u00f3n con investigaciones oficiales, \u00f3rdenes judiciales y procedimientos legales si es necesario para el procesamiento legal o la aplicaci\u00f3n de la ley. Cuando los gobiernos exigen legalmente datos de clientes a Usercentrics, Usercentrics se esfuerza por limitar la divulgaci\u00f3n. Usercentrics s\u00f3lo divulgar\u00e1 datos espec\u00edficos exigidos en virtud de la demanda legal pertinente.<\/p>\n<p>Si se viera obligada a revelar sus datos, Usercentrics se lo notificar\u00e1 de inmediato y le proporcionar\u00e1 una copia de la demanda, a menos que la ley se lo proh\u00edba.<\/p>\n<p>En el caso de que Usercentrics conf\u00ede a terceros la recopilaci\u00f3n, el tratamiento y el uso de datos en el marco del tratamiento delegado de conformidad con el art\u00edculo 28 del RGPD, dicho tratamiento se llevar\u00e1 a cabo exclusivamente de conformidad con las disposiciones legales sobre protecci\u00f3n de datos.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-10\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-10-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-10-content\">\n        X. Cumplimiento con la California Consumer Privacy Act     <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-10-content\"\n         aria-labelledby=\"uc-accordion-item-10-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <p>Adem\u00e1s de lo mencionado anteriormente, las siguientes disposiciones se aplican espec\u00edficamente a los residentes de California (EE. UU.).<\/p>\n<p>Las leyes de privacidad de California garantizan a los usuarios derechos espec\u00edficos sobre su informaci\u00f3n personal. En esta secci\u00f3n se describen los derechos de los consumidores y se explica c\u00f3mo ejercerlos, siempre con las excepciones previstas por la ley.<\/p>\n<p>1. Sus derechos en virtud de la Ley de privacidad de California<\/p>\n<ul>\n<li>Derecho a conocer la informaci\u00f3n personal recopilada, vendida o compartida (\u201cDerecho a conocer\u201d)<\/li>\n<\/ul>\n<p>Tiene derecho a solicitar saber qu\u00e9 informaci\u00f3n personal hemos recopilado sobre usted, lo que incluye:<\/p>\n<ul>\n<li>Las categor\u00edas de informaci\u00f3n personal recopilada<\/li>\n<li>Las categor\u00edas de fuentes de las que se recopila la informaci\u00f3n personal<\/li>\n<li>El prop\u00f3sito comercial de recopilar o vender la informaci\u00f3n personal<\/li>\n<li>Las categor\u00edas de terceros con los que se comparte la informaci\u00f3n personal<\/li>\n<li>Los datos personales espec\u00edficos recopilados sobre usted que est\u00e1n permitidos por la ley<\/li>\n<\/ul>\n<ul>\n<li>Derecho a solicitar la eliminaci\u00f3n de informaci\u00f3n personal (\u201cDerecho de eliminaci\u00f3n\u201d)<\/li>\n<\/ul>\n<p>Tiene derecho a solicitar que eliminemos cualquier informaci\u00f3n personal que recopilemos, con ciertas excepciones. Una vez que recibamos su solicitud <strong>y verifiquemos su identidad<\/strong>, eliminaremos (y pediremos a nuestros proveedores de servicios que eliminen) su informaci\u00f3n personal de nuestros registros, a menos que se aplique una excepci\u00f3n.<\/p>\n<ul>\n<li>Derecho a corregir informaci\u00f3n personal imprecisa (\u201cDerecho a corregir\u201d)<\/li>\n<\/ul>\n<p>Tiene derecho a solicitar la correcci\u00f3n de la informaci\u00f3n personal inexacta que mantenemos sobre usted o a actualizar la informaci\u00f3n que tenemos en nuestros archivos.<\/p>\n<ul>\n<li>Derecho a rechazar la venta o el uso compartido de su informaci\u00f3n personal<\/li>\n<\/ul>\n<p>Tiene derecho a exigir que no venda ni comparta su informaci\u00f3n personal. Usercentrics no vende informaci\u00f3n personal, incluida la informaci\u00f3n personal de menores de 16 a\u00f1os. Usted puede hacer uso de su derecho de optar por que no se venda ni comparta su informaci\u00f3n personal haciendo clic en el enlace \u201cNo vender o compartir mi informaci\u00f3n personal\u201d en la parte inferior de la p\u00e1gina.<\/p>\n<ul>\n<li>Derecho a la no discriminaci\u00f3n por el ejercicio de sus derechos de privacidad<\/li>\n<\/ul>\n<p>Usted tiene derecho a ser protegido contra la discriminaci\u00f3n por ejercer sus derechos. No le discriminaremos por ejercer sus derechos.<\/p>\n<ul>\n<li>Derecho a limitar el uso de informaci\u00f3n personal confidencial<\/li>\n<\/ul>\n<p>Usercentrics no utiliza informaci\u00f3n personal sensible de ninguna manera que requiera ofrecer el derecho de limitar su uso.<\/p>\n<p>2. C\u00f3mo enviar una solicitud para ejercer su derecho a conocer, eliminar o corregir<\/p>\n<p>Puede enviar su solicitud mediante un correo electr\u00f3nico a <a href=\"mailto:privacy@usercentrics.com\">privacy@usercentrics.com<\/a>. Compararemos la informaci\u00f3n que nos env\u00ede con la que figura en nuestros registros para asegurarnos de que su solicitud cumple con la definici\u00f3n de \u00absolicitud de consumidor verificable\u00bb en virtud de las leyes de privacidad de California. A continuaci\u00f3n, responderemos a su solicitud de acuerdo con lo estipulado.<\/p>\n<ul>\n<li><strong>Plazo y formato de la respuesta<\/strong><\/li>\n<\/ul>\n<p>Usercentrics se esfuerza por responder a una solicitud en un plazo de cuarenta y cinco (45) d\u00edas a partir de su recepci\u00f3n. Si Usercentrics requiere m\u00e1s tiempo (hasta 90 d\u00edas), se le informar\u00e1 por escrito del motivo y el plazo de la extensi\u00f3n. Cualquier informaci\u00f3n proporcionada solo abarcar\u00e1 el periodo de doce (12) meses anterior a la recepci\u00f3n de la solicitud verificable. Si procede, la respuesta tambi\u00e9n explicar\u00e1 los motivos por los que Usercentrics no puede dar respuesta a una solicitud. Para las solicitudes de portabilidad de datos, Usercentrics seleccionar\u00e1 un formato para proporcionar la informaci\u00f3n personal que sea f\u00e1cilmente utilizable y que permita la transmisi\u00f3n de la informaci\u00f3n de una entidad a otra sin obst\u00e1culos. Usercentrics no cobra una tarifa para procesar o responder a la solicitud verificable, a menos que sea excesiva, repetitiva o manifiestamente infundada. Si Usercentrics determina que la solicitud merece una retribuci\u00f3n, justificaremos el motivo y le facilitaremos una estimaci\u00f3n del coste antes de completarla.<\/p>\n<p>3. Ni\u00f1os menores de 16 a\u00f1os<\/p>\n<p>Usercentrics no recopila ni divulga conscientemente la informaci\u00f3n personal de ni\u00f1os menores de 16 a\u00f1os. Como se ha indicado anteriormente, Usercentrics tampoco vende ni comparte informaci\u00f3n personal, incluida la informaci\u00f3n personal de ni\u00f1os menores de 16 a\u00f1os.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-11\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-11-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-11-content\">\n        XI. MENORES DE EDAD    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-11-content\"\n         aria-labelledby=\"uc-accordion-item-11-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <p>Nuestros servicios no est\u00e1n dirigidos a menores de 13 a\u00f1os. No recopilamos deliberadamente informaci\u00f3n de ni\u00f1os menores de 13 a\u00f1os. Si no supera este l\u00edmite de edad, no utilice los servicios ni nos proporcione su informaci\u00f3n personal. Si es padre de un ni\u00f1o por debajo del l\u00edmite de edad y se entera de que su hijo ha proporcionado informaci\u00f3n personal a Usercentrics, env\u00edenos un correo electr\u00f3nico a <a href=\"mailto:datenschutz@usercentrics.com\">datenschutz@usercentrics.com<\/a> e insista en ejercer sus derechos de acceso, correcci\u00f3n, cancelaci\u00f3n u oposici\u00f3n. Si reside en California y es menor de 18 a\u00f1os, y desea borrar el contenido disponible de forma p\u00fablica, env\u00edenos un correo a <a href=\"mailto:datenschutz@usercentrics.com\">datenschutz@usercentrics.com<\/a>.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-12\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-12-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-12-content\">\n        XII. PRESENCIA ONLINE EN REDES SOCIALES    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-12-content\"\n         aria-labelledby=\"uc-accordion-item-12-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <p>Mantenemos presencia online en redes sociales con el fin de comunicarnos con clientes y partes interesadas, entre otros, por esos canales y para proveer de informaci\u00f3n sobre nuestros productos y servicios.<\/p>\n<p>Los datos de los usuarios son normalmente procesados por las redes sociales con fines de investigaci\u00f3n de mercado y publicitarios. De esta manera, los perfiles de uso pueden ser creados en base a los intereses de los usuarios. Para este fin, las cookies y otros identificadores son almacenados en los ordenadores de los usuarios. Con base en estos perfiles de uso, los anuncios, por ejemplo, son puestos en los perfiles de redes sociales, pero tambi\u00e9n en sitios web de terceras partes.<\/p>\n<p>Como parte del funcionamiento de nuestras presencias online, es posible que podamos acceder a informaci\u00f3n como las estad\u00edsticas sobre el uso de nuestras presencias online, que son proporcionadas por las redes sociales. Estas estad\u00edsticas son agregadas y pueden incluir, en particular, informaci\u00f3n demogr\u00e1fica y datos sobre la interacci\u00f3n con nuestras presencias online y las publicaciones y contenidos distribuidos a trav\u00e9s de ellas. En la lista que figura a continuaci\u00f3n encontrar\u00e1 detalles y enlaces a los datos de las redes sociales a los que podemos acceder como operadores de las presencias en l\u00ednea.<\/p>\n<p>La base legal del tratamiento de datos es el Art. 6 p\u00e1rr. 1 apdo. a y b del RGPD, con el fin de estar en contacto e informar a nuestros clientes, y para llevar a cabo medidas precontractuales con futuros clientes y partes interesadas.<\/p>\n<p>Para la base jur\u00eddica del tratamiento de datos llevado a cabo por las redes sociales bajo su propia responsabilidad, por favor, refi\u00e9rase a la informaci\u00f3n de protecci\u00f3n de datos de la red social correspondiente. Los links a continuaci\u00f3n tambi\u00e9n le proveen con m\u00e1s informaci\u00f3n sobre el tratamiento de datos correspondiente y las opciones a las que objetar.<\/p>\n<p>Nos gustar\u00eda destacar que las peticiones de protecci\u00f3n de datos pueden hacerse valer m\u00e1s eficientemente ante el proveedor de la red social correspondiente, dado que s\u00f3lo estos proveedores tienen acceso a los datos y pueden tomar las medidas apropiadas directamente. A continuaci\u00f3n hay una lista con informaci\u00f3n sobre las redes sociales en las que operamos presencias online:<\/p>\n<ul>\n<li>Facebook (EE. UU. y Canad\u00e1: Facebook Inc., 1601 Willow Road, Menlo Park, California 94025, EE. UU.; resto de pa\u00edses: Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dubl\u00edn 2, Irlanda).\n<ul>\n<li>Operaci\u00f3n de la Fanpage de Facebook en responsabilidad conjunta con base en un acuerdo de tratamiento conjunto de datos personales (denominado Page Insights Supplement en relaci\u00f3n al controlador).<\/li>\n<li>Informaci\u00f3n sobre los datos de insight tratados y la opci\u00f3n de contacto en caso de peticiones de protecci\u00f3n de datos: <a href=\"https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data<\/a><\/li>\n<li>Pol\u00edtica de privacidad: <a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/about\/privacy\/<\/a><\/li>\n<li>Opt-out: <a href=\"https:\/\/www.facebook.com\/settings?tab=ads\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/settings?tab=ads<\/a> and <a href=\"http:\/\/www.youronlinechoices.com\" target=\"_blank\" rel=\"noopener\">http:\/\/www.youronlinechoices.com<\/a>.<\/li>\n<\/ul>\n<\/li>\n<li>Instagram (Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dubl\u00edn 2, Irlanda).\n<ul>\n<li>Pol\u00edtica de privacidad: <a href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\" rel=\"noopener\">https:\/\/help.instagram.com\/519522125107875<\/a><\/li>\n<\/ul>\n<\/li>\n<li>Google\/ YouTube (Google Ireland Limited, Gordon House, Barrow Street, Dubl\u00edn 4, Irlanda).\n<ul>\n<li>Pol\u00edtica de privacidad: <a href=\"https:\/\/policies.google.com\/privacy?hl=es\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy?hl=es<\/a><\/li>\n<li>Opt-out: <a href=\"https:\/\/www.google.com\/settings\/ads\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/settings\/ads<\/a>.<\/li>\n<\/ul>\n<\/li>\n<li>Twitter (Twitter International Company, One Cumberland Place, Fenian Street, Dubl\u00edn 2, D02 AX07 Irlanda).\n<ul>\n<li>Pol\u00edtica de privacidad: <a href=\"https:\/\/twitter.com\/es\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/twitter.com\/es\/privacy<\/a><\/li>\n<li>Opt-Out: <a href=\"https:\/\/twitter.com\/personalization\" target=\"_blank\" rel=\"noopener\">https:\/\/twitter.com\/personalization<\/a>.<\/li>\n<\/ul>\n<\/li>\n<li>LinkedIn (LinkedIn Ireland Unlimited Company Wilton Place, Dubl\u00edn 2, Irlanda).\n<ul>\n<li>Operaci\u00f3n de la p\u00e1gina de la compa\u00f1\u00eda en LinkedIn en responsabilidad conjunta con base en un acuerdo de tratamiento conjunto de datos personales (denominado Page Insights Joint Controller Addendum).<\/li>\n<li>Informaci\u00f3n sobre los datos de insight tratados y la opci\u00f3n de contacto en caso de peticiones de protecci\u00f3n de datos: <a href=\"https:\/\/legal.linkedin.com\/pages-joint-controller-addendum\" target=\"_blank\" rel=\"noopener\">https:\/\/legal.linkedin.com\/pages-joint-controller-addendum<\/a><\/li>\n<li>Pol\u00edtica de privacidad: <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a><\/li>\n<li>Opt-out: <a href=\"https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out<\/a>.<\/li>\n<\/ul>\n<\/li>\n<li>Google my business\n<ul>\n<li>We operate a so-called Google My Business entry. Should you find us in this way, we make use of the information service offered by Google and the services of Google Ireland Limited, Gordon House, Barrow Street, Dubl\u00edn 4, Ireland (hereinafter \u00abGoogle\u00bb).<\/li>\n<li>Operamos una entrada denominada Google My Business. Si nos encuentra de esta forma, empleamos el servicio de informaci\u00f3n ofrecido por Google y los servicios de Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlanda (a partir de ahora \u00abGoogle\u00bb).<\/li>\n<li>Nos gustar\u00eda destacar que usted usa el sitio de Google por su propia responsabilidad. Esto aplica particularmente al uso de las funciones sociales e interactivas (p. ej., comentarios, comparticiones, evaluaciones, mensajes directos). Cuando visita e interact\u00faa con nuestra entrada de Google My Business, Google tambi\u00e9n recopila su direcci\u00f3n IP y otra informaci\u00f3n que est\u00e1 presente en su dispositivo en forma de las denominadas cookies. Esta informaci\u00f3n es usada para proveernos a nosotros, como operadores de la entrada de Google My Business, con informaci\u00f3n estad\u00edstica sobre el uso de los servicios de Google. Los datos recopilados sobre usted en este contexto ser\u00e1n tratados por Google y pueden ser transferidos a pa\u00edses fuera de la Uni\u00f3n Europea. Google, generalmente, describe qu\u00e9 informaci\u00f3n recibe y c\u00f3mo es usada en su pol\u00edtica de privacidad. Google provee informaci\u00f3n m\u00e1s detallada en su pol\u00edtica de privacidad:<\/li>\n<li><a href=\"https:\/\/policies.google.com\/privacy?hl=es\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de privacidad de Google<\/a><\/li>\n<li>No sabemos c\u00f3mo Google usa los datos de la visita para sus propios prop\u00f3sitos, hasta qu\u00e9 punto son asignadas las actividades de los usuarios individuales, por cu\u00e1nto tiempo almacena Google estos datos y si estos datos son transferidos a terceras partes. Al acceder a servicios de Google, la direcci\u00f3n IP asignada a su terminal es transferida a Google. Google tambi\u00e9n almacena informaci\u00f3n de los terminales de los usuarios; esto puede permitir a Google asignar direcciones IP a usuarios individuales o cuentas de usuarios.<\/li>\n<li>Si nos contacta mediante nuestra entrada de Google My Business u otro servicio de Google por mensaje directo, no podemos descartar la posibilidad de que estos mensajes sean tambi\u00e9n le\u00eddos y evaluados por Google (tanto por empleados como autom\u00e1ticamente). Es por eso que recomendamos que no se nos provea informaci\u00f3n personal ah\u00ed. En cambio, otro medio de comunicaci\u00f3n deber\u00eda ser empleado tan pronto como sea posible. Eliminamos nuestras conversaciones no m\u00e1s tarde de 14 d\u00edas despu\u00e9s de la \u00faltima actividad en el chat o inmediatamente despu\u00e9s de cambiar a otro canal de comunicaci\u00f3n. El uso de este servicio est\u00e1 sujeto a la pol\u00edtica de privacidad de Google, a la que usted, a trav\u00e9s del uso, ha accedido.<\/li>\n<li>Nosotros, como proveedores de la entrada de Google My Business, no recopilamos ni tratamos ning\u00fan otro dato de su uso de este servicio de Google. Aparte de eso, no usamos ninguna funci\u00f3n de Google en nuestro sitio web.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-13\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-13-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-13-content\">\n        XIII. TRANSFERENCIA DE DATOS A TERCEROS PA\u00cdSES    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-13-content\"\n         aria-labelledby=\"uc-accordion-item-13-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <p>Como se ha explicado en esta pol\u00edtica de privacidad, usamos servicios cuyos proveedores est\u00e1n parcialmente ubicados en los denominados como terceros pa\u00edses (fuera de la Uni\u00f3n Europea o del \u00c1rea Econ\u00f3mica Europea) o tratan datos personales ah\u00ed, es decir, pa\u00edses cuyos niveles de protecci\u00f3n de datos no se corresponden con aquellos de la Uni\u00f3n Europea. Cuando \u00e9ste sea el caso, y la Comisi\u00f3n Europea no haya publicado una decisi\u00f3n de adecuaci\u00f3n (art. 45 del RGPD) para estos pa\u00edses, hemos tomado las precauciones necesarias para garantizar un nivel adecuado de protecci\u00f3n de datos para cualquier transferencia de datos de acuerdo al Art. 44 y siguientes del RGPD. Estas incluyen, entre otras, cl\u00e1usulas contractuales est\u00e1ndar de la Uni\u00f3n Europea o regulaciones internas de protecci\u00f3n de datos vinculantes.<\/p>\n<p>Si una transferencia a un tercer pa\u00eds es provista y no hay decisiones de adecuaci\u00f3n o protecciones apropiadas, es posible y existe un riesgo de que las autoridades en el respectivo tercer pa\u00eds (p. ej., servicios de inteligencia) consigan acceso a los datos transferidos con el fin de recopilarlos y analizarlos, y que la aplicabilidad de los derechos en relaci\u00f3n a sus datos no puedan ser garantizados.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-14\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-14-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-14-content\">\n        XIV. ENLACES A TERCEROS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-14-content\"\n         aria-labelledby=\"uc-accordion-item-14-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <p>Ocasionalmente, y en base a nuestro criterio, podemos incluir u ofrecer productos o servicios de terceros en nuestro sitio web. Estos sitios de terceros tienen pol\u00edticas de privacidad independientes. Por lo tanto, no asumimos ninguna responsabilidad por el contenido y las actividades de estos sitios web vinculados. No obstante, buscamos proteger la integridad de nuestro sitio web y agradecemos cualquier comentario sobre estos sitios.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-15\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-15-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-15-content\">\n        XV. SUS DERECHOS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-15-content\"\n         aria-labelledby=\"uc-accordion-item-15-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <p>Si tratamos sus datos personales, puede ejercer los siguientes derechos una vez le hayamos identificado correctamente:<\/p>\n<ul>\n<li>Derecho de informaci\u00f3n (Art\u00edculo 15 del RGPD, \u00a7 34 BDSG alemana)<\/li>\n<li>Derecho de eliminaci\u00f3n (Art\u00edculo 17 del RGPD, \u00a7 35 BDSG)<\/li>\n<li>Derecho de rectificaci\u00f3n (Art\u00edculo 16 del RGPD, Section 34 BDSG)<\/li>\n<li>Derecho de restricci\u00f3n al tratamiento (Art\u00edculo 18 del RGPD)<\/li>\n<li>Derecho a portabilidad de datos (Art\u00edculo 20 del RGPD)<\/li>\n<li>Derecho de retirar el consetimiento (Art\u00edculo 7(3) del RGPD)<\/li>\n<li>Derecho de oposici\u00f3n (Art\u00edculo 21 del RGPD).<\/li>\n<\/ul>\n<p>Con el fin de ejercer sus derechos aqu\u00ed descritos, puede contactarnos en cualquier momento usando los detalles de contacto listados debajo de \u201c<a href=\"#policy-top\">Nombre de la persona responsable<\/a>\u201d.<\/p>\n<p>Tambi\u00e9n tiene el derecho a presentar una reclamaci\u00f3n a la autoridad supervisora de protecci\u00f3n de datos responsable de nosotros. Puede contactar con la autoridad de protecci\u00f3n de datos en su lugar de residencia, que despu\u00e9s dirigir\u00e1 su petici\u00f3n a la autoridad competente.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-16\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-16-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-16-content\">\n        XVI. SEGURIDAD E INTEGRIDAD DE LOS DATOS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-16-content\"\n         aria-labelledby=\"uc-accordion-item-16-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <p>Proteger la informaci\u00f3n que nos proporciona o que recibimos sobre usted es nuestra prioridad. Adoptamos las medidas de seguridad adecuadas para proteger su informaci\u00f3n de p\u00e9rdida, mal uso, acceso no autorizado, alteraci\u00f3n, divulgaci\u00f3n o destrucci\u00f3n. Usercentrics ha tomado medidas para garantizar la confidencialidad, integridad, disponibilidad y resiliencia continuas de los sistemas y servicios que tratan informaci\u00f3n personal, y restaurar\u00e1 la disponibilidad y el acceso a la informaci\u00f3n en caso de un incidente f\u00edsico o t\u00e9cnico de forma oportuna.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-17\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-17-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-17-content\">\n        XVII. ACTUALIZACIONES    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-17-content\"\n         aria-labelledby=\"uc-accordion-item-17-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            <p>Nos reservamos el derecho de actualizar ocasionalmente esta pol\u00edtica de privacidad. En caso de realizar cambios materiales que restrinjan los derechos u obligaciones de Usercentrics en virtud de esta pol\u00edtica de privacidad, publicaremos un aviso claro en esta secci\u00f3n de esta pol\u00edtica de privacidad cuando se actualicen.<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n\n\n\n<p>Clique <a href=\"https:\/\/usercentrics.com\/es\/privacy-policy\/\">aqu\u00ed<\/a> para ver la pol\u00edtica de privacidad v\u00e1lida a partir de 16 mayo de 2024.<br \/>\nClique <a href=\"https:\/\/usercentrics.com\/es\/privacy-policy-until-march-2024\/\" target=\"_blank\" rel=\"noopener nofollow\">aqu\u00ed<\/a> para consultar la Pol\u00edtica de privacidad previa, v\u00e1lida hasta 22 de marzo de 2024.<\/p>\n\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"editor_notices":[],"footnotes":""},"class_list":["post-3920","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<title>Pol\u00edtica de privacidad de Usercentrics<\/title>\n<meta name=\"description\" content=\"En la pol\u00edtica de privacidad de Usercentrics encontrar\u00e1 toda la informaci\u00f3n necesaria sobre los datos recopilados y procesados, as\u00ed como las tecnolog\u00edas que se utilizan en este sitio web.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad de Usercentrics\" \/>\n<meta property=\"og:description\" content=\"En la pol\u00edtica de privacidad de Usercentrics encontrar\u00e1 toda la informaci\u00f3n necesaria sobre los datos recopilados y procesados, as\u00ed como las tecnolog\u00edas que se utilizan en este sitio web.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/usercentrics.com\/es\/privacy-policy-until-may-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Consent Management Platform (CMP) Usercentrics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/usercentrics\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T08:17:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/usercentrics.com\/es\/wp-content\/uploads\/sites\/6\/2024\/09\/Asset-93-100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pol\u00edtica de privacidad de Usercentrics\" \/>\n<meta name=\"twitter:description\" content=\"En la pol\u00edtica de privacidad de Usercentrics encontrar\u00e1 toda la informaci\u00f3n necesaria sobre los datos recopilados y procesados, as\u00ed como las tecnolog\u00edas que se utilizan en este sitio web.\" \/>\n<meta name=\"twitter:site\" content=\"@usercentrics\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/usercentrics.com\\\/es\\\/privacy-policy-until-may-2024\\\/\",\"url\":\"https:\\\/\\\/usercentrics.com\\\/es\\\/privacy-policy-until-may-2024\\\/\",\"name\":\"Pol\u00edtica de privacidad de Usercentrics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/usercentrics.com\\\/es\\\/#website\"},\"datePublished\":\"2024-05-21T15:31:39+00:00\",\"dateModified\":\"2024-09-11T08:17:58+00:00\",\"description\":\"En la pol\u00edtica de privacidad de Usercentrics encontrar\u00e1 toda la informaci\u00f3n necesaria sobre los datos recopilados y procesados, as\u00ed como las tecnolog\u00edas que se utilizan en este sitio web.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":\"https:\\\/\\\/usercentrics.com\\\/es\\\/privacy-policy-until-may-2024\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/usercentrics.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/usercentrics.com\\\/es\\\/\",\"name\":\"Consent Management Platform (CMP) Usercentrics\",\"description\":\"Consent Management Platform (CMP) Usercentrics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/usercentrics.com\\\/es\\\/?s={search_term_string}\"}}],\"inLanguage\":\"es\"}]}<\/script>","yoast_head_json":{"title":"Pol\u00edtica de privacidad de Usercentrics","description":"En la pol\u00edtica de privacidad de Usercentrics encontrar\u00e1 toda la informaci\u00f3n necesaria sobre los datos recopilados y procesados, as\u00ed como las tecnolog\u00edas que se utilizan en este sitio web.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de privacidad de Usercentrics","og_description":"En la pol\u00edtica de privacidad de Usercentrics encontrar\u00e1 toda la informaci\u00f3n necesaria sobre los datos recopilados y procesados, as\u00ed como las tecnolog\u00edas que se utilizan en este sitio web.","og_url":"https:\/\/usercentrics.com\/es\/privacy-policy-until-may-2024\/","og_site_name":"Consent Management Platform (CMP) Usercentrics","article_publisher":"https:\/\/www.facebook.com\/usercentrics","article_modified_time":"2024-09-11T08:17:58+00:00","og_image":[{"width":1201,"height":631,"url":"https:\/\/usercentrics.com\/es\/wp-content\/uploads\/sites\/6\/2024\/09\/Asset-93-100.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Pol\u00edtica de privacidad de Usercentrics","twitter_description":"En la pol\u00edtica de privacidad de Usercentrics encontrar\u00e1 toda la informaci\u00f3n necesaria sobre los datos recopilados y procesados, as\u00ed como las tecnolog\u00edas que se utilizan en este sitio web.","twitter_site":"@usercentrics","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/usercentrics.com\/es\/privacy-policy-until-may-2024\/","url":"https:\/\/usercentrics.com\/es\/privacy-policy-until-may-2024\/","name":"Pol\u00edtica de privacidad de Usercentrics","isPartOf":{"@id":"https:\/\/usercentrics.com\/es\/#website"},"datePublished":"2024-05-21T15:31:39+00:00","dateModified":"2024-09-11T08:17:58+00:00","description":"En la pol\u00edtica de privacidad de Usercentrics encontrar\u00e1 toda la informaci\u00f3n necesaria sobre los datos recopilados y procesados, as\u00ed como las tecnolog\u00edas que se utilizan en este sitio web.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":"https:\/\/usercentrics.com\/es\/privacy-policy-until-may-2024\/"}]},{"@type":"WebSite","@id":"https:\/\/usercentrics.com\/es\/#website","url":"https:\/\/usercentrics.com\/es\/","name":"Consent Management Platform (CMP) Usercentrics","description":"Consent Management Platform (CMP) Usercentrics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/usercentrics.com\/es\/?s={search_term_string}"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/usercentrics.com\/es\/wp-json\/wp\/v2\/pages\/3920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usercentrics.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/usercentrics.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/usercentrics.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/usercentrics.com\/es\/wp-json\/wp\/v2\/comments?post=3920"}],"version-history":[{"count":0,"href":"https:\/\/usercentrics.com\/es\/wp-json\/wp\/v2\/pages\/3920\/revisions"}],"wp:attachment":[{"href":"https:\/\/usercentrics.com\/es\/wp-json\/wp\/v2\/media?parent=3920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}