{"id":7324,"date":"2026-03-20T12:55:03","date_gmt":"2026-03-20T11:55:03","guid":{"rendered":"https:\/\/stage.usercentrics.com\/pt\/?page_id=7324"},"modified":"2026-03-20T13:12:24","modified_gmt":"2026-03-20T12:12:24","slug":"privacy-policy-valid-until-march-15-2026","status":"publish","type":"page","link":"https:\/\/usercentrics.com\/pt\/privacy-policy-valid-until-march-15-2026\/","title":{"rendered":"Declara\u00e7\u00e3o de prote\u00e7\u00e3o de dados v\u00e1lida at\u00e9 15 de mar\u00e7o de 2026"},"content":{"rendered":"<div class=\"uc-flex-row\" style=\"--padding-top: 0px; --padding-bottom: var(--wp--preset--spacing--5-xl);\">\n<div class=\"uc-flex-column\" style=\"--column-size: var(--column-size-12);--i:1;\">\n    \n\n<script>\n  window.UC_UI_SUPPRESS_CMP_DISPLAY = true;\n<\/script>\n\n\n\n<div style=\"height:64px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-declaracao-de-protecao-de-dados-valida-ate-15-de-marco-de-2026\">Declara\u00e7\u00e3o de prote\u00e7\u00e3o de dados v\u00e1lida at\u00e9 15 de mar\u00e7o de 2026<\/h1>\n\n\n\n<p><span style=\"font-weight: 400;\">www.usercentrics.com<\/span><\/p>\n\n\n\n<p>\u00daltima atualiza\u00e7\u00e3o: 12 de novembro de 2025<\/p>\n\n\n\n<p>A sua privacidade \u00e9 importante para n\u00f3s. Esta Pol\u00edtica de Privacidade abrange o que recolhemos e a forma como usamos, divulgamos, transferimos e armazenamos as suas informa\u00e7\u00f5es.<\/p>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-1\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-1-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-1-content\">\n        I. NOME DA PESSOA RESPONS\u00c1VEL    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-1-content\"\n         aria-labelledby=\"uc-accordion-item-1-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<p>A pessoa respons\u00e1vel conforme o RGPD e outras leis de prote\u00e7\u00e3o de dados dos estados-membros, bem como outros dispositivos legais de prote\u00e7\u00e3o de dados \u00e9 a<\/p>\n\n\n\n<p>Usercentrics GmbH<br>Sendlinger Stra\u00dfe 7<br>80331 Munique<br>Alemanha<br>e-mail: <a href=\"mailto:datenschutz@usercentrics.com\">datenschutz@usercentrics.com<\/a> | website: www.usercentrics.com<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-2\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-2-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-2-content\">\n        II. ENCARREGADO DE PROTEC\u00c7\u00c3O DE DADOS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-2-content\"\n         aria-labelledby=\"uc-accordion-item-2-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<h3 class=\"wp-block-heading\" id=\"h-1-dados-de-contacto\">1. Dados de contacto<\/h3>\n\n\n\n<p>O nosso Encarregado de Protec\u00e7\u00e3o de Dados (EPD) ou Data Protection Officer (DPO) pode ser contatado conforme segue:<\/p>\n\n\n\n<p><strong>SECUWING GmbH &amp; Co. KG<\/strong><br>Maximilian Hartung<\/p>\n\n\n\n<p>Frauentorstr. 9<br>86152 Augsburg<br>Alemanha<\/p>\n\n\n\n<p>E-mail: <a href=\"mailto:epost@datenschutz-agentur.de\">epost@datenschutz-agentur.de<\/a> | Telefone: +49 821 90786450 | Fax: +49 821 90786459<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-representante-rgpd-do-reino-unido\">2. Representante RGPD do Reino Unido<\/h3>\n\n\n\n<p>O nosso representante UK-GDPR \u00e9:<\/p>\n\n\n\n<p>Rickert Services Ltd UK<\/p>\n\n\n\n<p>&#8211; Usercentrics &#8211;<br>PO Box 1487<br>Peterborough<br>PE1 9XX<br>Reino Unido<br><a href=\"mailto:art-27-rep-usercentrics@rickert-services.uk\">art-27-rep-usercentrics@rickert-services.uk<\/a><\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-3\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-3-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-3-content\">\n        III. INFORMA\u00c7\u00d5ES GERAIS SOBRE A RECOLHA E O PROCESSAMENTO DOS SEUS DADOS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-3-content\"\n         aria-labelledby=\"uc-accordion-item-3-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<h3 class=\"wp-block-heading\">1. \u00c2mbito do Processamento<\/h3>\n\n\n\n<p>Em princ\u00edpio, apenas recolhemos e utilizamos dados pessoais na medida em que tal \u00e9 necess\u00e1rio para a disponibiliza\u00e7\u00e3o de um site funcional bem como dos nossos conte\u00fados e servi\u00e7os. O processamento de dados pessoais dos nossos utilizadores ocorre regularmente apenas ap\u00f3s consentimento do utilizador. Uma exce\u00e7\u00e3o vale para os casos em que uma recolha pr\u00e9via de consentimento n\u00e3o \u00e9 poss\u00edvel por motivos f\u00e1ticos e o processamento dos dados seja autorizado por dispositivos legais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Fundamenta\u00e7\u00e3o legal<\/h3>\n\n\n\n<p>Na medida em que obtemos autoriza\u00e7\u00e3o da pessoa afetada para processamento de dados pessoais, art. 6, al\u00ednea 1, s. 1, letra a, do RGPD vale como fundamenta\u00e7\u00e3o legal.<\/p>\n\n\n\n<p>No processamento de dados pessoais necess\u00e1rios para a execu\u00e7\u00e3o de contrato em que a pessoa afetada \u00e9 parte, o art. 6, al\u00ednea 1, s. 1, letra b do RGPD vale como fundamenta\u00e7\u00e3o legal. Isto tamb\u00e9m se aplica para processamentos necess\u00e1rios para a realiza\u00e7\u00e3o de medidas preliminares.<\/p>\n\n\n\n<p>Na medida em que um processamento de dados pessoais \u00e9 necess\u00e1rio para o cumprimento de obriga\u00e7\u00e3o legal a que nossa empresa est\u00e1 sujeita, o art. 6, al\u00ednea 1, s. 1, letra c do RGPD vale como fundamenta\u00e7\u00e3o legal.<\/p>\n\n\n\n<p>Se o processamento for necess\u00e1rio para salvaguarda de interesse justificado de nossa empresa ou de terceiro e se os interesses, direitos e liberdades fundamentais da pessoa afetada n\u00e3o predominarem sobre aquele interesse, o art. 6, al\u00ednea 1, s. 1, letra f do RGPD vale como fundamenta\u00e7\u00e3o legal para o processamento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Armazenamento e elimina\u00e7\u00e3o dos seus dados<\/h3>\n\n\n\n<p>Em princ\u00edpio, armazenamos apenas dados pessoais pelo tempo necess\u00e1rio ao cumprimento de obriga\u00e7\u00f5es contratuais ou legais para as quais recolhemos os dados. Depois disso, exclu\u00edmos os dados imediatamente, a n\u00e3o ser que ainda sejam necess\u00e1rios at\u00e9 ao vencimento do per\u00edodo de limita\u00e7\u00e3o estatut\u00e1ria para evidencia\u00e7\u00e3o em solicita\u00e7\u00f5es formuladas nos termos da lei civil ou devido a obriga\u00e7\u00f5es de reten\u00e7\u00e3o estatut\u00e1ria.<\/p>\n\n\n\n<p>Para fins de evid\u00eancia, devemos reter os dados contratuais por seis anos contados do final do ano em que o seu relacionamento comercial se encerrar. Nesse ponto, quaisquer reivindica\u00e7\u00f5es se tornar\u00e3o prescritas, no mais tardar, at\u00e9 essa data, de acordo com o per\u00edodo de limita\u00e7\u00e3o estatut\u00e1ria.<\/p>\n\n\n\n<p>Mesmo depois desse per\u00edodo, ainda ser\u00e1 preciso armazenar alguns dos seus dados por motivos contabil\u00edsticos. Somos imbu\u00eddos de cumprir essa exig\u00eancia por quest\u00f5es de obriga\u00e7\u00f5es envolvendo documenta\u00e7\u00e3o legal, as quais poder\u00e3o advir do C\u00f3digo Comercial Alem\u00e3o, do C\u00f3digo Fiscal Alem\u00e3o, da Lei Banc\u00e1ria Alem\u00e3, da Lei de Lavagem de Dinheiro Alem\u00e3 e da Lei de Negocia\u00e7\u00e3o de Valores Mobili\u00e1rios Alem\u00e3. Os per\u00edodos especificados na lei para a reten\u00e7\u00e3o de documentos s\u00e3o de dois a dez anos.<\/p>\n\n\n\n<p>Exclu\u00edmos ou bloqueamos os dados pessoais do titular t\u00e3o logo o objetivo do armazenamento seja satisfeito. Os dados tamb\u00e9m podem ser armazenados se fornecidos pelo legislador europeu ou nacional nos termos das normas, leis ou regulamentos da UE aos quais a nossa empresa est\u00e1 sujeita. O bloqueio ou a exclus\u00e3o dos dados tamb\u00e9m ocorre quando expira o per\u00edodo de armazenamento fixado pelos padr\u00f5es acima mencionados, exceto se houver uma necessidade de armazenamento adicional dos dados para a finaliza\u00e7\u00e3o ou cumprimento de um contrato.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Aten\u00e7\u00e3o<\/h3>\n\n\n\n<p>Para a utiliza\u00e7\u00e3o deste site e a utiliza\u00e7\u00e3o da Plataforma de Gest\u00e3o de Consentimento incorporada, os seus dados de consentimento ser\u00e3o processados. Utilizamos a Plataforma Google Cloud, fornecida pela Google Cloud EMEA Ltd. Os servidores localizam-se na Alemanha e na B\u00e9lgica.<\/p>\n\n\n\n<p>Gostar\u00edamos de informa-lo que n\u00e3o est\u00e1 exclu\u00edda a possibilidade dos dados serem transmitidos aos EUA e estarem expostos a um acesso das autoridades de seguran\u00e7a conforme 50 U. S. C. \u00a71881(b)(4), 50 U.S.C. \u00a7 1881a (= FISA 702).<\/p>\n\n\n\n<p>Na eventualidade dos dados pessoais serem transferidos para os EUA ou algum pa\u00eds terceiro, tomamos as medidas necess\u00e1rias com a Google de acordo com o art. 44 et seq do RGPD. Mais informa\u00e7\u00f5es podem ser encontradas nas <a href=\"https:\/\/cloud.google.com\/terms\/cloud-privacy-notice?hl=de\" target=\"_blank\" rel=\"noopener\">Refer\u00eancias \u00e0 prote\u00e7\u00e3o de dados<\/a> da Google. Al\u00e9m disso, foram tomadas outras medidas de seguran\u00e7a adicionais para garantir a seguran\u00e7a dos dados.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-4\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-4-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-4-content\">\n        IV. DISPONIBILIZA\u00c7\u00c3O DO SITE E ELABORA\u00c7\u00c3O DE ARQUIVOS DE REGISTOS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-4-content\"\n         aria-labelledby=\"uc-accordion-item-4-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<h3 class=\"wp-block-heading\">1.&nbsp;\u00c2mbito do processamento<\/h3>\n\n\n\n<p>Em cada acesso ao nosso website, o nosso sistema recolhe automaticamente dados e informa\u00e7\u00f5es do sistema do computador acessante. Estes s\u00e3o, por exemplo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>informa\u00e7\u00f5es sobre o tipo e vers\u00e3o de seu navegador da internet,<\/li>\n\n\n\n<li>o sistema operativo de seu computador ou smartphone,<\/li>\n\n\n\n<li>o seu provedor de servi\u00e7os de internet,<\/li>\n\n\n\n<li>o seu endere\u00e7o de IP,<\/li>\n\n\n\n<li>a data e hora do seu acesso,<\/li>\n\n\n\n<li>localiza\u00e7\u00e3o geogr\u00e1fica,<\/li>\n\n\n\n<li>websites a partir das quais foi direcionado a n\u00f3s,<\/li>\n\n\n\n<li>websites que visita a partir do nosso website,<\/li>\n\n\n\n<li>quando aplic\u00e1vel &#8211; URL referenciador no site do parceiro.<\/li>\n<\/ul>\n\n\n\n<p>Recolhemos tais informa\u00e7\u00f5es t\u00e9cnicas nos chamados \u201clog files\u201d (ficheiros de registo), para que o nosso website lhe seja mostrada corretamente e n\u00f3s, em caso de eventuais problemas, possamos detectar as causas, para a otimiza\u00e7\u00e3o t\u00e9cnica dos nossos websites e para fins de seguran\u00e7a dos nossos sistemas de computadores e redes. Nestes fins, temos um interesse leg\u00edtimo no processamento de dados em conformidade com o art. 6, al\u00ednea 1, s. 1, letra f do RGPD.<\/p>\n\n\n\n<p>Os dados ser\u00e3o eliminados assim que n\u00e3o sejam mais necess\u00e1rios para a obten\u00e7\u00e3o dos fins de sua recolha. Normalmente, estas informa\u00e7\u00f5es t\u00e9cnicas s\u00e3o eliminadas ou tornadas irreconhec\u00edveis ap\u00f3s, no m\u00e1ximo, sete dias.<\/p>\n\n\n\n<p>A recolha de dados para a disponibiliza\u00e7\u00e3o do site e o armazenamento dos dados em ficheiros de registo s\u00e3o absolutamente necess\u00e1rios para a opera\u00e7\u00e3o do website.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-5\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-5-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-5-content\">\n        V. SOLICITA\u00c7\u00d5ES DE CONTATO PARA OBTEN\u00c7\u00c3O DE INFORMA\u00c7\u00d5ES SOBRE PRODUTOS, UMA DEMONSTRA\u00c7\u00c3O OU OUTRAS CONSULTAS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-5-content\"\n         aria-labelledby=\"uc-accordion-item-5-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<h3 class=\"wp-block-heading\">1. Descri\u00e7\u00e3o e \u00e2mbito do processamento de dados<\/h3>\n\n\n\n<p>No nosso site, pode entrar em contato connosco por meio de diversas possibilidades: entre outros, formul\u00e1rio de contato, pedir demonstra\u00e7\u00e3o, or\u00e7amento, informa\u00e7\u00f5es de produtos, guias. Caso fa\u00e7a uso destas op\u00e7\u00f5es, os dados inseridos na m\u00e1scara de entrada s\u00e3o-nos transmitidos e armazenados. Al\u00e9m dos dados espec\u00edficos da m\u00e1scara de entrada, o endere\u00e7o de IP e a data e a hora da consulta s\u00e3o recolhidos e armazenados.<\/p>\n\n\n\n<p>Como alternativa, \u00e9 poss\u00edvel o contato por e-mail. Neste caso, seus dados pessoais enviados por e-mail ser\u00e3o armazenados.<\/p>\n\n\n\n<p>Neste contexto, n\u00e3o ocorre transmiss\u00e3o dos dados a terceiros, a n\u00e3o ser quando isto for necess\u00e1rio para o processamento do pedido (por exemplo, ferramenta de agendamento de demonstra\u00e7\u00e3o). Em todos os casos, os dados ser\u00e3o utilizados exclusivamente para o processamento da conversa, a menos que seja acordado o contr\u00e1rio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Fundamento legal para o processamento<\/h3>\n\n\n\n<p>O fundamento legal para o processamento dos dados \u00e9, em geral, o consentimento do utilizador, art. 6, al\u00ednea 1, s. 1, letra a do RGPD.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Finalidade do processamento de dados<\/h3>\n\n\n\n<p>O processamento dos dados pessoais da m\u00e1scara de entrada destina-se unicamente para o processamento da sua consulta. Em caso de contato por e-mail, tamb\u00e9m h\u00e1 o interesse justificado necess\u00e1rio no processamento dos dados.<\/p>\n\n\n\n<p>Os outros dados pessoais processados durante o procedimento de envio destinam-se a evitar mau uso do formul\u00e1rio de contato e garantir a seguran\u00e7a dos nossos sistemas de tecnologia da informa\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Dura\u00e7\u00e3o do armazenamento<\/h3>\n\n\n\n<p>Caso tenha agendado uma demonstra\u00e7\u00e3o, pedido informa\u00e7\u00f5es de produtos ou um or\u00e7amento, reservamos o direito de armazenar os dados por dois anos para medir a nossa rentabilidade de vendas e de marketing. De resto, eliminamos os dados assim que n\u00e3o sejam mais necess\u00e1rios para a obten\u00e7\u00e3o dos fins de sua recolha. Para os dados pessoais inseridos no formul\u00e1rio de contato e aqueles que forem enviados por e-mail, este ser\u00e1 o caso quando a respectiva conversa consigo for conclu\u00edda. A conversa estar\u00e1 conclu\u00edda quando for poss\u00edvel inferir das circunst\u00e2ncias que a situa\u00e7\u00e3o afetada foi solucionada de forma conclusiva.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Revoga\u00e7\u00e3o de consentimento e possibilidade de elimina\u00e7\u00e3o<\/h3>\n\n\n\n<p>Tem a possibilidade de, a qualquer momento, revogar seu consentimento para o processamento dos seus dados pessoais. Se entrar em contato connosco por e-mail, poder\u00e1 contestar o armazenamento dos seus dados pessoais a qualquer momento.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-6\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-6-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-6-content\">\n        VI. NEWSLETTER, RECOMENDA\u00c7\u00d5ES DE PRODUTOS, WEBINARS, INQU\u00c9RITOS A CLIENTES, PORTAL DE PARCEIROS E TESTES A\/B    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-6-content\"\n         aria-labelledby=\"uc-accordion-item-6-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<h3 class=\"wp-block-heading\">1. Newsletter<\/h3>\n\n\n\n<p>Ao inscrever-SE para receber a Newsletter, os dados inseridos na m\u00e1scara de entrada tamb\u00e9m ser\u00e3o armazenados para que receba a Newsletter. A base legal para esse processamento \u00e9 o art. 6, al\u00ednea 1, s. 1, letra a do RGPD. O seu endere\u00e7o de e-mail, o hor\u00e1rio da assinatura e o endere\u00e7o IP usados para fazer a assinatura ser\u00e3o mantidos enquanto for assinante da nossa Newsletter. Esse servi\u00e7o \u00e9 disponibilizado por meio de uma aceita\u00e7\u00e3o dupla. Por conseguinte, receber\u00e1 um e-mail contendo um link com o qual poder\u00e1 confirmar se \u00e9 o propriet\u00e1rio ou n\u00e3o do endere\u00e7o de e-mail e se deseja ser notificado por meio do nosso servi\u00e7o de e-mail. \u00c9 poss\u00edvel desistir do servi\u00e7o a qualquer momento atrav\u00e9s do email <a href=\"mailto:unsubcribe@usercentrics.com\">unsubcribe@usercentrics.com<\/a> ou optando por cancelar a assinatura usando o link fornecido nas newsletters a qualquer momento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Recomenda\u00e7\u00f5es de produtos<\/h3>\n\n\n\n<p>Ser\u00e1 informado pela Usercentrics sobre altera\u00e7\u00f5es relevantes relacionadas aos Servi\u00e7os, como a implementa\u00e7\u00e3o de fun\u00e7\u00f5es adicionais, por e-mail, se adquirir um produto Usercentrics. A base legal para isso \u00e9 o art. 6, al\u00ednea 1, letra f do RGPD, em conjunto com o par\u00e1grafo 7, al\u00ednea 3 da Lei contra a Concorr\u00eancia Desleal (Gesetz gegen den unlauteren Wettbewerb &#8211; UWG), justificado pelo nosso interesse em enviar-lhe ofertas individuais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Webinars<\/h3>\n\n\n\n<p>A Usercentrics oferece periodicamente webinars, nos quais pode inscrever-se atrav\u00e9s do nosso site. Nesses casos, os dados inseridos no formul\u00e1rio de inscri\u00e7\u00e3o durante o processo de registo ser\u00e3o usados pela Usercentrics para fins relacionados ao webinar, bem como para comunica\u00e7\u00f5es sobre o webinar e outros t\u00f3picos relevantes. Se o webinar for organizado em conjunto com um parceiro, os dados poder\u00e3o ser compartilhados com ele. Os dados s\u00e3o processados na base legal do consentimento, art. 6, al\u00ednea 1, s. 1, letra a do RGPD. Tem o direito de revogar o seu consentimento para o processamento de dados a qualquer momento entrando em contato com <a href=\"mailto:unsubscribe@usercentrics.com\">unsubscribe@usercentrics.com<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-participacao-na-investigacao\">4. Participa\u00e7\u00e3o na investiga\u00e7\u00e3o<\/h3>\n\n\n\n<p>Se efetuar uma encomenda connosco, incluindo a inscri\u00e7\u00e3o numa conta de teste, poderemos utilizar o seu endere\u00e7o de e-mail para lhe enviar um convite para participar em atividades de feedback de clientes, tais como inqu\u00e9ritos de satisfa\u00e7\u00e3o, entrevistas a utilizadores ou outras formas de investiga\u00e7\u00e3o de produtos. Estas atividades ajudam-nos a compreender melhor a sua experi\u00eancia e a melhorar os nossos produtos e servi\u00e7os.<\/p>\n\n\n\n<p>O fundamento jur\u00eddico para isto \u00e9 o art. 6.\u00ba, al\u00ednea 1 letra a do RGPD, onde forneceu o seu consentimento. Em alguns casos, o art. 6.\u00ba, al\u00ednea 1 letra f do RGPD tamb\u00e9m poder\u00e1 aplicar-se, com base no nosso interesse leg\u00edtimo em melhorar constantemente o nosso servi\u00e7o e garantir uma experi\u00eancia de utilizador de alta qualidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Plataforma de gest\u00e3o de prefer\u00eancias<\/h3>\n\n\n\n<p>Usamos a plataforma de gest\u00e3o de prefer\u00eancias da Usercentrics para fornecer-lhe, como destinat\u00e1rio da nossa newsletter e outros tipos de comunica\u00e7\u00e3o, a op\u00e7\u00e3o de escolher quais os tipos de comunica\u00e7\u00e3o que deseja receber. Pode alterar suas configura\u00e7\u00f5es e prefer\u00eancias a qualquer momento. Ao usar este servi\u00e7o, ser\u00e3o armazenados o seu endere\u00e7o de e-mail e as suas decis\u00f5es de prefer\u00eancias. Esses dados s\u00e3o usados para que possamos enviar comunica\u00e7\u00f5es com base nas suas prefer\u00eancias. Os dados mencionados acima s\u00e3o processados somente com o seu consentimento (art. 6, al\u00ednea 1, s. 1, letra a do RGPD). Pode revogar o seu consentimento a qualquer momento. Os dados n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Portal de Parceiros<\/h3>\n\n\n\n<p>Utilizamos o Portal de Parceiros da Usercentrics como uma ferramenta de gest\u00e3o de parceiros. Ao utilizar o Portal de Parceiros, os dados pessoais dos nossos Parceiros podem ser processados. Estes podem incluir as seguintes informa\u00e7\u00f5es: nome, endere\u00e7o de e-mail, nome e informa\u00e7\u00f5es da empresa, informa\u00e7\u00f5es sobre acordos assinados (dados do acordo, n\u00edvel do parceiro, etc.), informa\u00e7\u00f5es sobre os clientes do parceiro (incluindo endere\u00e7o de e-mail e nome), comportamento no Portal de Parceiros e, possivelmente, informa\u00e7\u00f5es transaccionais. Estes dados s\u00e3o processados de forma a cumprir a nossa rela\u00e7\u00e3o contratual. Os dados s\u00e3o mantidos durante o tempo necess\u00e1rio para cumprir o objetivo. Os dados recolhidos n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><b>7<\/b>. Pedidos de suporte<\/h3>\n\n\n\n<p>Quando cria um ticket de suporte com a Usercentrics, iremos processar os dados inseridos no ticket, para efeitos de avalia\u00e7\u00e3o e resposta ao seu pedido. Neste caso utilizamos como sistema de suporte o servi\u00e7o Zendesk fornecido pela Zendesk, Inc., 1019 Market Street, San Francisco, CA 94103, EUA (doravante Zendesk), que permite aos utilizadores comunicar com a Usercentrics. Para isso ser\u00e3o processados os dados inseridos no ticket (Nome, Endere\u00e7o de E-Mail, etc.) bem como o Endere\u00e7o IP. A base jur\u00eddica para o tratamento \u00e9 o consentimento (Art. 6.\u00ba, n.\u00ba 1, s. 1, lit. a do RGPD). Ao criar um ticket atrav\u00e9s do Zendesk, aceita tamb\u00e9m a utiliza\u00e7\u00e3o das seguintes funcionalidades no Zendesk: Zendesk IA avan\u00e7ada, Triagem inteligente, Intelig\u00eancia no painel de contexto, IA generativa para agentes, Sugest\u00f5es de macro para administradores, Resposta autom\u00e1tica e observa\u00e7\u00f5es internas, IA generativa para a central de ajuda. Pode encontrar mais informa\u00e7\u00f5es sobre o uso de IA pela Zendesk <a href=\"https:\/\/support.zendesk.com\/hc\/pt-br\/articles\/5729714731290-Informa%C3%A7%C3%B5es-de-uso-de-dados-de-IA-do-Zendesk?_ga=2.225815002.1146878627.1719315251-609650956.1719315251&amp;_gl=1%2Ai8atxc%2A_ga%2AMTg2Nzk4OTM0My4xNzAyMzg1NzIy%2A_ga_FBP7C61M6Z%2AMTcxOTMxNDcwNi4xMC4xLjE3MTkzMTUzMDYuNjAuMC4w%2A_gcl_au%2AMTIxODM0NTQ3Mi4xNzE4ODY4MjQz#h_01H128YHC41CMTD1GKDAW2Y2N4\">aqui<\/a>. Os dados ser\u00e3o eliminados logo que deixem de ser necess\u00e1rios para atingir a finalidade da sua recolha.<\/p>\n\n\n\n<p>Para mais informa\u00e7\u00f5es sobre a forma como os dados s\u00e3o tratados pela Zendesk, pode visitar a <a href=\"https:\/\/www.zendesk.com.br\/company\/agreements-and-terms\/privacy-notice\/\">pol\u00edtica de privacidade<\/a> da Zendesk ou contactar a Zendesk atrav\u00e9s do e-mail <a href=\"mailto:privacy@zendesk.com\">privacy@zendesk.com<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-analise-do-site-e-da-politica-de-privacidade\">8. An\u00e1lise do site e da pol\u00edtica de privacidade<\/h3>\n\n\n\n<p>Sempre que solicitar uma verifica\u00e7\u00e3o do seu site ou da Pol\u00edtica de Privacidade, processaremos os dados introduzidos no formul\u00e1rio e verificaremos o seu site com o objetivo de fornecer os resultados da an\u00e1lise solicitada.<\/p>\n\n\n\n<p>Ao utilizar o Privacy Policy Scan, a verifica\u00e7\u00e3o \u00e9 realizada com a ajuda do <a href=\"https:\/\/everworker.ai\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Everwork<\/a>, uma solu\u00e7\u00e3o potenciada por IA. Para mais informa\u00e7\u00f5es sobre a forma como o Everwork trata os seus dados pessoais, consulte a sua <a href=\"https:\/\/everworker.ai\/legal\/privacy-policy\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">pol\u00edtica de privacidade<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-testes-a-b\">9. Testes A\/B<\/h3>\n\n\n\n<p>Em alguns casos, poderemos estar a realizar testes A\/B nos nossos websites. Os testes ocorrem sem que sejam tratados dados pessoais. Para realizar o teste A\/B, \u00e9 definido um cookie (uc_experiments), que cont\u00e9m a vers\u00e3o do website que cada indiv\u00edduo est\u00e1 a ver. Os dados do teste n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-7\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-7-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-7-content\">\n        VII. TORNA-SE CLIENTE OU PARCEIRO DA USERCENTRICS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-7-content\"\n         aria-labelledby=\"uc-accordion-item-7-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<h3 class=\"wp-block-heading\">1. Descri\u00e7\u00e3o e \u00e2mbito do processamento de dados<\/h3>\n\n\n\n<p>Pode tornar-se um cliente ou parceiro da Usercentrics. Os seguintes dados s\u00e3o recolhidos durante o processo de inscri\u00e7\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>o seu endere\u00e7o de e-mail,<\/li>\n\n\n\n<li>nome e apelido,<\/li>\n\n\n\n<li>se for o caso, v\u00ednculo \u00e0 empresa,<\/li>\n\n\n\n<li>informa\u00e7\u00f5es de pagamento (se for o caso, da empresa),<\/li>\n\n\n\n<li>outros dados que lhe pedimos, e<\/li>\n\n\n\n<li>se for o caso, dados que obtemos no \u00e2mbito do relacionamento comercial.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">2. Fundamento legal para o processamento<\/h3>\n\n\n\n<p>O fundamento legal para o processamento dos dados \u00e9, com consentimento do utilizador, o art. 6, al\u00ednea 1, s. 1, letra a do RGPD, bem como art. 6, al\u00ednea 1, s. 1, letra b do RGPD, pois o registo \u00e9 necess\u00e1rio para o cumprimento de um contrato ou a realiza\u00e7\u00e3o de medidas pr\u00e9-contratuais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Finalidade do processamento de dados<\/h3>\n\n\n\n<p>O registo \u00e9 necess\u00e1rio para o cumprimento do contrato do cliente ou parceiro ou para a realiza\u00e7\u00e3o de medidas pr\u00e9-contratuais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Possibilidade de revoga\u00e7\u00e3o e elimina\u00e7\u00e3o<\/h3>\n\n\n\n<p>Enquanto cliente, tem a possibilidade, a qualquer momento, de remover a sua conta. Os seus dados armazenados podem ser alterados por si a qualquer momento. Se os dados forem necess\u00e1rios para o cumprimento de um contrato ou a realiza\u00e7\u00e3o de medidas pr\u00e9-contratuais, a elimina\u00e7\u00e3o precoce dos dados somente \u00e9 poss\u00edvel na medida em que n\u00e3o haja obriga\u00e7\u00f5es contratuais ou legais que obstem uma elimina\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-links-incorporados\">5. Links incorporados<\/h3>\n\n\n\n<p>No momento da inscri\u00e7\u00e3o nos nossos servi\u00e7os, o utilizador deve ter em aten\u00e7\u00e3o que avaliamos o comportamento do pr\u00f3prio. Gravamos o comportamento da sua campanha. Os links incorporados cont\u00eam par\u00e2metros UTM e outros identificadores que identificam todos os par\u00e2metros dos \u201ccliques\u201d.<\/p>\n\n\n\n<p>Os par\u00e2metros UTM e outros identificadores permitem-nos adicionar extens\u00f5es rastre\u00e1veis aos URLs. Os par\u00e2metros s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Meio: este par\u00e2metro descreve o meio no qual o link est\u00e1 incorporado. Exemplos: correio eletr\u00f3nico, redes sociais ou website.<\/li>\n\n\n\n<li>Fonte: com este par\u00e2metro UTM definimos a fonte do link. Pode tratar-se de newsletters, website, aplica\u00e7\u00f5es ou canais de redes sociais.<\/li>\n\n\n\n<li>Campanha: este tipo de par\u00e2metro UTM \u00e9 utilizado para identificar as campanhas activas. Por exemplo, se enviamos ao utilizador uma newsletter todos os meses, as newsletters individuais podem ser avaliadas separadamente.<\/li>\n\n\n\n<li>Termo: palavras-chave, para que o link possa ser identificado mais facilmente.<\/li>\n\n\n\n<li>Conte\u00fado: numa campanha, inserimos diferentes elementos a serem monitorizados para os identificarmos claramente e os avaliarmos separadamente. Exemplos: bot\u00e3o, imagem ou v\u00eddeo.<\/li>\n\n\n\n<li>Cup\u00f5es: identificadores adicionados a uma campanha para acompanhar as intera\u00e7\u00f5es com um elemento da campanha ou aplicar um desconto.<\/li>\n<\/ul>\n\n\n\n<p>Os identificadores s\u00e3o gerados pelos prestadores de servi\u00e7os listados na sec\u00e7\u00e3o IX da presente Pol\u00edtica de privacidade. Utilizamos os identificadores em combina\u00e7\u00e3o com eventos de convers\u00e3o, como a cria\u00e7\u00e3o de uma conta (por exemplo, se come\u00e7ar um per\u00edodo de teste ou se fizer um upgrade para uma conta premium) para informar os fornecedores de servi\u00e7os sobre o evento em rela\u00e7\u00e3o aos identificadores fornecidos.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-8\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-8-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-8-content\">\n        VIII. COOKIES E TECNOLOGIAS DE RASTREAMENTO    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-8-content\"\n         aria-labelledby=\"uc-accordion-item-8-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<h3 class=\"wp-block-heading\">1. O que s\u00e3o cookies?<\/h3>\n\n\n\n<p>Cookies de navegador da internet: Um cookie de navegador \u00e9 um pequeno ficheiro de texto que \u00e9 enviado de um site ao seu computador ou dispositivo m\u00f3vel onde s\u00e3o armazenados pelo seu navegador de internet. Cookies de navegador podem armazenar informa\u00e7\u00f5es como o seu endere\u00e7o IP ou outro identificador, o tipo de navegador e informa\u00e7\u00f5es sobre os conte\u00fados que acessa nos servi\u00e7os digitais e com os quais interage. Pelo armazenamento de tais informa\u00e7\u00f5es, cookies de navegador podem armazenar as suas prefer\u00eancias e configura\u00e7\u00f5es para servi\u00e7os online e analisar como utiliza servi\u00e7os online.<\/p>\n\n\n\n<p>Tecnologias de rastreamento: Beacons da internet\/Gifs, pixels, tags de websites, scripts.<\/p>\n\n\n\n<p>E-mails e aplica\u00e7\u00f5es m\u00f3veis podem conter pequenos ficheiros de imagens transparentes ou linhas de c\u00f3digo para registar como interage com eles. Estas informa\u00e7\u00f5es s\u00e3o utilizadas para ajudar os publicadores de sites e apps a melhor analisar e melhorar os seus servi\u00e7os.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Utiliza\u00e7\u00e3o, fundamenta\u00e7\u00e3o legal e finalidade<\/h3>\n\n\n\n<p>Empregamos cookies para estruturar o site para que tenha mais facilidade de utiliza\u00e7\u00e3o. Alguns elementos de nosso site exigem que o navegador acessante tamb\u00e9m possa ser identificado mesmo depois de uma troca de sites.<\/p>\n\n\n\n<p>Os cookies, bem como o armazenamento dos dados no armazenamento local, permitem, assim, apenas funcionalidades que contribuem para uma experi\u00eancia de utilizador positiva no nosso site. N\u00e3o utilizamos cookies com dados pessoais sem consentimento.<\/p>\n\n\n\n<p>Al\u00e9m disso, utilizamos cookies que permitem uma an\u00e1lise do comportamento de navega\u00e7\u00e3o dos utilizadores.<\/p>\n\n\n\n<p>No acesso ao nosso site, o utilizador \u00e9 informado sobe a utiliza\u00e7\u00e3o de cookies para fins de an\u00e1lise e o seu consentimento para o processamento dos dados pessoais utilizados neste contexto \u00e9 recolhido.<\/p>\n\n\n\n<p>A base legal para o processamento de dados pessoais utilizando cookies tecnicamente necess\u00e1rios \u00e9 o artigo 6, al\u00ednea 1, s. 1, letra F do RGPD. O objetivo do uso de cookies tecnicamente necess\u00e1rios \u00e9 facilitar o uso de sites pelos utilizadores. Alguns recursos do nosso site n\u00e3o podem ser oferecidos sem o uso de cookies. Para isso, \u00e9 necess\u00e1rio que o navegador seja reconhecido, mesmo ap\u00f3s uma quebra de p\u00e1gina. Precisamos de cookies para as seguintes aplica\u00e7\u00f5es: aceita\u00e7\u00e3o das configura\u00e7\u00f5es de idioma. Os dados do utilizador recolhidos por meio de cookies tecnicamente necess\u00e1rios n\u00e3o ser\u00e3o usados para criar perfis de utilizador.<\/p>\n\n\n\n<p>O fundamento legal para o processamento de dados pessoais com o uso de cookies para fins de an\u00e1lise \u00e9 o consentimento do utilizador art. 6, al\u00ednea 1, letra a do RGPD.<\/p>\n\n\n\n<p>A utiliza\u00e7\u00e3o dos cookies de an\u00e1lise destina-se \u00e0 melhoraria da qualidade do nosso site e dos seus conte\u00fados. Por meio de cookies de an\u00e1lise, descobrimos como o site \u00e9 utilizado e podemos, assim, melhorar a nossa oferta constantemente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Dura\u00e7\u00e3o do armazenamento, possibilidade de revoga\u00e7\u00e3o e elimina\u00e7\u00e3o<\/h3>\n\n\n\n<p>Os cookies s\u00e3o armazenados no computador do utilizador e transmitidos para nosso lado. Por isto, enquanto utilizador, tem pleno controlo sobre a utiliza\u00e7\u00e3o de cookies. Por meio de altera\u00e7\u00e3o das configura\u00e7\u00f5es no seu navegador, pode desativar ou restringir a transmiss\u00e3o de cookies. Cookies j\u00e1 armazenados podem ser eliminados a qualquer momento. Isto tamb\u00e9m pode ocorrer de forma automatizada. Se os cookies forem desativados parav o nosso site, provavelmente n\u00e3o ser\u00e1 poss\u00edvel utilizar plenamente todas as suas funcionalidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Destinat\u00e1rios dos dados<\/h3>\n\n\n\n<p>A transmiss\u00e3o dos dados por n\u00f3s recolhidos acontece somente quando necess\u00e1ria ao cumprimento do contrato ou por motivos de provisionamento da funcionalidade t\u00e9cnica do site, ou se houver outra base legal para a referida transmiss\u00e3o.<\/p>\n\n\n\n<p>Em princ\u00edpio, o processamento dos seus dados \u00e9 executado por n\u00f3s mesmos. Em alguns casos, no entanto, recorremos tamb\u00e9m a prestadores de servi\u00e7os. Al\u00e9m dos mencionados nesta pol\u00edtica de privacidade, os prestadores de servi\u00e7os podem incluir, em particular, data centers que armazenam o nosso site e bancos de dados, prestadores de servi\u00e7os de TI que mant\u00eam os nossos sistemas, e empresas de consultoria. Se compartilharmos dados com os prestadores de servi\u00e7os, o uso dos dados dever\u00e1 ser restrito ao cumprimento das suas tarefas. Al\u00e9m de cuidadosamente selecionados e comissionados por n\u00f3s, os prestadores de servi\u00e7os mant\u00eam um v\u00ednculo contratual com as nossas instru\u00e7\u00f5es, implementaram medidas t\u00e9cnicas e organizacionais adequadas para proteger os direitos dos titulares dos dados e s\u00e3o regularmente monitorizados por n\u00f3s.<\/p>\n\n\n\n<p>Al\u00e9m disso, a ocorr\u00eancia da divulga\u00e7\u00e3o pode estar relacionada a consultas oficiais, ordens judiciais e processos legais se necess\u00e1ria para fins de a\u00e7\u00e3o judicial ou aplica\u00e7\u00e3o da lei. Quando governos fazem uma demanda legal por dados de clientes da Usercentrics, a Usercentrics empreende todos os esfor\u00e7os para limitar a sua divulga\u00e7\u00e3o. A Usercentrics far\u00e1 a libera\u00e7\u00e3o de dados espec\u00edficos apenas se exigida pela autoridade legal competente.<\/p>\n\n\n\n<p>Caso seja obrigada a divulgar os seus dados, a Usercentrics notific\u00e1-lo-\u00e1 imediatamente e fornecer\u00e1 uma c\u00f3pia da exig\u00eancia, exceto se legalmente proibida de assim faz\u00ea-lo.<\/p>\n\n\n\n<p>Se a Usercentrics comissionar a terceiros a recolha, o processamento e o uso de dados dentro do \u00e2mbito do processamento comissionado, de acordo com o art. 28 do RGPD, tal tamb\u00e9m ocorrer\u00e1 exclusivamente em conformidade com as disposi\u00e7\u00f5es legais sobre prote\u00e7\u00e3o de dados.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-9\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-9-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-9-content\">\n        IX. TECNOLOGIAS IMPLEMENTADAS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-9-content\"\n         aria-labelledby=\"uc-accordion-item-9-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<h3 class=\"wp-block-heading\">1. Tecnologias de terceiros usadas no site<\/h3>\n\n\n\n<div class=\"uc-embed\" uc-layout=\"1\" uc-embed-type=\"all\"\n                                                                       uc-embed-show-toggle=\"true\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Zapier<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o Zapier como software de automa\u00e7\u00e3o de fluxos de trabalho. O servi\u00e7o \u00e9 fornecido pela Zapier Inc., 548 Market St., # 62411, San Francisco, California 94104, Estados Unidos da Am\u00e9rica. Este servi\u00e7o \u00e9 utilizado para transferir informa\u00e7\u00f5es introduzidas em formul\u00e1rios no nosso website para os nossos sistemas. Al\u00e9m disso, informa\u00e7\u00f5es como o endere\u00e7o IP podem ser tratadas atrav\u00e9s do servi\u00e7o. O fundamento jur\u00eddico para a utiliza\u00e7\u00e3o deste servi\u00e7o \u00e9 o interesse leg\u00edtimo, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea f) do RGPD, uma vez que o servi\u00e7o \u00e9 necess\u00e1rio para transferir os dados introduzidos para os nossos sistemas internos. Os dados ser\u00e3o eliminados assim que deixem de ser necess\u00e1rios para cumprir a finalidade da recolha. Este servi\u00e7o poder\u00e1 transferir dados para fora da UE\/EEE. Nesse caso, assin\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os.<\/p>\n\n\n\n<p>Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pela Zapier, pode consultar a&nbsp;<a href=\"https:\/\/zapier.com\/privacy\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidade<\/a> da Zapier ou contactar a Zapier atrav\u00e9s do endere\u00e7o <a href=\"mailto:privacy@zapier.com\">privacy@zapier.com<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Leads do LinkedIn<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o de gera\u00e7\u00e3o de leads fornecido pelo LinkedIn. Ao inscrever-se em eventos ou conte\u00fados da Usercentrics no LinkedIn, trataremos os seus dados. O endere\u00e7o de e-mail ser\u00e1 utilizado para o envio dos recursos e para publicidade direta, bem como para iniciar contactos no contexto dos produtos e servi\u00e7os que oferecemos. Os dados tamb\u00e9m s\u00e3o partilhados com o Google Ads para fins de ressegmenta\u00e7\u00e3o. Os dados ser\u00e3o tamb\u00e9m partilhados com Expandi.io (ProfitSoft B.V., Meerenakkerplein 51, Eindhoven, 5652BJ, Pa\u00edses Baixos), para a automatiza\u00e7\u00e3o da comunica\u00e7\u00e3o e intera\u00e7\u00e3o no LinkedIn. Para mais informa\u00e7\u00f5es, clique <a href=\"https:\/\/expandi.io\/privacy-notice\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">aqui<\/a>.<br>A recolha dos dados n\u00e3o ocorre no website da Usercentrics, mas sim nos formul\u00e1rios de inscri\u00e7\u00e3o no LinkedIn. O fundamento jur\u00eddico \u00e9 o consentimento, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea a) do RGPD. Pode revogar o seu consentimento a qualquer momento.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Personio<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o Personio como software de gest\u00e3o de candidatos. O servi\u00e7o \u00e9 fornecido pela Personio GmbH, Rundfunkplatz 4, 80335 Munique, Alemanha. O fundamento jur\u00eddico \u00e9 o consentimento, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea a) do RGPD. Pode revogar o seu consentimento a qualquer momento. Os dados ser\u00e3o armazenados durante um per\u00edodo de 60 dias ap\u00f3s a conclus\u00e3o do processo de candidatura. Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pela Personio, consulte a&nbsp;<a href=\"https:\/\/www.personio.com\/privacy-policy\/\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidade<\/a> da Personio ou contacte a Personio atrav\u00e9s do endere\u00e7o privacy@personio.com.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Storylane<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o prestado pela Storylane Inc. como uma plataforma de demonstra\u00e7\u00e3o interativa. O servi\u00e7o \u00e9 fornecido pela Storylane Inc., 2261 Market Street #4813, S\u00e3o Francisco, CA 94114, Estados Unidos da Am\u00e9rica. O servi\u00e7o \u00e9 utilizado como uma plataforma de demonstra\u00e7\u00e3o interativa, para fornecer demonstra\u00e7\u00f5es no &#8216;website&#8217;, que os utilizadores podem usar para se guiarem atrav\u00e9s da demonstra\u00e7\u00e3o do produto. Ao utilizar este servi\u00e7o, podem ser processados dados como o endere\u00e7o IP. A base jur\u00eddica \u00e9 o consentimento, Art. 6\u00ba, par\u00e1grafo 1, al\u00ednea a) do RGPD. Pode revogar o seu consentimento a qualquer momento. Este servi\u00e7o pode transferir dados para fora da UE\/EEE. Para esse caso, assinal\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os.<br>Para mais informa\u00e7\u00f5es sobre a forma como os dados s\u00e3o processados pela Storylane, pode consultar a <a href=\"https:\/\/www.storylane.io\/privacy-policy\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">pol\u00edtica de privacidade<\/a> da Storylane ou contactar a Storylane em <a href=\"mailto:privacy@storylane.io\">privacy@storylane.io<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Zoom<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o fornecido pela Zoom como servi\u00e7o de videoconfer\u00eancia. O servi\u00e7o \u00e9 fornecido pela Zoom Video Communications Inc., 55 Almaden Boulevard, 6th Floor, San Jose, CA 95113, Estados Unidos da Am\u00e9rica. O servi\u00e7o \u00e9 utilizado como servi\u00e7o de videoconfer\u00eancia para alojar webinars e outros tipos de videoconfer\u00eancias. O fundamento jur\u00eddico \u00e9 o consentimento, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea a) do RGPD. Pode revogar o seu consentimento a qualquer momento. Este servi\u00e7o poder\u00e1 transferir dados para fora da UE\/EEE. Nesse caso, assin\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os, que est\u00e1 inclu\u00eddo na <a href=\"https:\/\/www.dataprivacyframework.gov\/list\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">Lista de Equadramentos de Privacidade dos Dados<\/a>.<\/p>\n\n\n\n<p>Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pela Zoom, pode consultar a <a href=\"https:\/\/explore.zoom.us\/en\/privacy\/\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidade<\/a> da Zoom ou contactar a Zoom atrav\u00e9s do endere\u00e7o privacy@zoom.us.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Salesforce<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o Salesforce fornecido pela Salesforce, Erika-Mann-Stra\u00dfe 31-37, 80636 Munique, Alemanha (doravante, Salesforce) para utilizar os servi\u00e7os Sales Cloud e Pardot. O Pardot \u00e9 um sistema de software CRM que fornece solu\u00e7\u00f5es para vendas, atendimento ao cliente e marketing. O Sales Cloud \u00e9 uma aplica\u00e7\u00e3o de vendas que permite \u00e0s empresas gerir contactos, clientes, oportunidades, or\u00e7amentos e encomendas. Para tal, ser\u00e3o tratados dados de conta, informa\u00e7\u00f5es de contacto e informa\u00e7\u00f5es sobre cursos (percentagem dos cursos e certifica\u00e7\u00e3o). O fundamento jur\u00eddico para o tratamento \u00e9 a execu\u00e7\u00e3o de um contrato (art. 6.\u00ba, al\u00ednea 1 s.1 letra b do RGPD), uma vez que este tratamento \u00e9 necess\u00e1rio para cumprir o contrato. Os dados ser\u00e3o eliminados assim que deixarem de ser necess\u00e1rios para cumprir a finalidade desta recolha. Este servi\u00e7o poder\u00e1 transferir dados para fora da UE\/do EEE. Nesse caso, assin\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os.<\/p>\n\n\n\n<p>Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pela Salesforce, pode consultar a <a href=\"https:\/\/www.salesforce.com\/company\/privacy\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">pol\u00edtica de privacidade<\/a> da Salesforce ou contactar a Salesforce atrav\u00e9s do endere\u00e7o <a href=\"mailto:privacy@salesforce.com\">privacy@salesforce.com<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>SayMine Technologies<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o MineOS fornecido pela SayMine Technologies Ltd., Alon 1 Tower, 94 Yigal Alon St, Tel Aviv-Yafo, 6789139, Israel (doravante SayMine) para fornecer uma ferramenta de gest\u00e3o de pedidos de privacidade de dados. Para o efeito, poder\u00e3o ser processados o nome, o endere\u00e7o de e-mail e outros dados partilhados pelo requerente. A base legal para o processamento \u00e9 a obriga\u00e7\u00e3o legal (Art. 6\u00ba, par\u00e1grafo 1\u00ba, al\u00ednea c do RGPD), uma vez que o servi\u00e7o \u00e9 utilizado de forma a cumprir as obriga\u00e7\u00f5es legais de resposta a pedidos de exerc\u00edcio dos direitos das pessoas em causa nos termos do RGPD. Os dados ser\u00e3o eliminados assim que deixarem de ser necess\u00e1rios para atingir a finalidade da sua recolha. Ao utilizar o formul\u00e1rio, estar\u00e1 ativo no website um servi\u00e7o captcha fornecido pela Google Ireland Limited.<\/p>\n\n\n\n<p>Para mais informa\u00e7\u00f5es sobre como os dados s\u00e3o processados pela SayMine, pode consultar a <a href=\"https:\/\/www.mineos.ai\/legal\/portal-privacy-policy\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">pol\u00edtica de privacidade<\/a> da SayMine ou contactar a SayMine em <a href=\"mailto:portal@saymine.com\">portal@saymine.com<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Stripe<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o fornecido pela Stripe como sistema de pagamento online. O servi\u00e7o \u00e9 fornecido pela Stripe, Inc., 3180 18th Street, San Francisco, CA 94110, Estados Unidos da Am\u00e9rica. O servi\u00e7o \u00e9 utilizado para permitir o processo de pagamentos no website. O fundamento jur\u00eddico \u00e9 a execu\u00e7\u00e3o de um contrato, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea b) do RGPD, uma vez que este servi\u00e7o \u00e9 necess\u00e1rio para poder finalizar o processo de compra. Ao utilizar este servi\u00e7o, dados como as informa\u00e7\u00f5es de pagamento (incluindo informa\u00e7\u00f5es do cart\u00e3o de pagamento), informa\u00e7\u00f5es de compra, bem como o endere\u00e7o IP, podem ser tratados. Este servi\u00e7o poder\u00e1 transferir dados para fora da UE\/EEE. Nesse caso, assin\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os, que est\u00e1 inclu\u00eddo na <a href=\"https:\/\/www.dataprivacyframework.gov\/list\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">Lista do Quadro de Privacidade dos Dados<\/a>.<\/p>\n\n\n\n<p>Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pela Stripe, pode consultar a <a href=\"https:\/\/stripe.com\/de\/privacy\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidade<\/a> da Stripe ou contactar a Stripe atrav\u00e9s do endere\u00e7o <a href=\"mailto:privacy@stripe.com\">privacy@stripe.com<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Chili Piper<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o fornecido pela Chili Piper como plataforma de reservas e reuni\u00f5es, de forma a proporcionar aos nossos utilizadores a possibilidade de agendarem reuni\u00f5es com as nossas equipas, bem como para videoconfer\u00eancias. O servi\u00e7o \u00e9 fornecido pela Chili Piper, Inc., 228 Park Ave. S., #78136, New York, New York 10003-1502, Estados Unidos da Am\u00e9rica. O fundamento jur\u00eddico \u00e9 o consentimento, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea a) do RGPD. Pode revogar o seu consentimento a qualquer momento. Ao utilizar estes servi\u00e7o, dados como a data, a hora e o t\u00edtulo da reuni\u00e3o, a lista de convidados, o nome pr\u00f3prio, o apelido e o endere\u00e7o de e-mail, podem ser tratados. Este servi\u00e7o poder\u00e1 transferir dados para fora da UE\/EEE. Nesse caso, aceit\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os.<\/p>\n\n\n\n<p>Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pela Chili Piper, pode consultar a <a href=\"https:\/\/www.chilipiper.com\/privacy-policy\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidade<\/a> da Chili Piper ou contactar a Chili Piper atrav\u00e9s do endere\u00e7o <a href=\"mailto:support@chilipiper.com\">support@chilipiper.com<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Pardot<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o fornecido pela Pardot como software de gest\u00e3o das rela\u00e7\u00f5es com clientes, para gerir a automa\u00e7\u00e3o de marketing e a gera\u00e7\u00e3o de leads. O servi\u00e7o \u00e9 fornecido pela Salesforce, Erika-Mann-Stra\u00dfe 31-37, 80636 Munique, Alemanha. O fundamento jur\u00eddico \u00e9 o consentimento, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea a) do RGPD. Pode revogar o seu consentimento a qualquer momento. Ao utilizar este servi\u00e7o, dados como o nome pr\u00f3prio e o apelido, informa\u00e7\u00f5es de contacto, endere\u00e7o de e-mail, informa\u00e7\u00f5es da empresa, bem como o endere\u00e7o IP, podem ser tratados.<\/p>\n\n\n\n<p>Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pela Pardot, pode consultar a <a href=\"https:\/\/www.salesforce.com\/company\/privacy\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidade<\/a> da Pardot ou contactar a Pardot atrav\u00e9s do endere\u00e7o <a href=\"mailto:privacy@salesforce.com\">privacy@salesforce.com<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Google Customer Match<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos a Segmenta\u00e7\u00e3o por lista de clientes da Google para efeitos de marketing e ressegmenta\u00e7\u00e3o. Este servi\u00e7o \u00e9 fornecido pela Google Ireland Limited, Gordon House, 4 Barrow Street, Dublin D04 E5W5, Irlanda. Ao utilizar este servi\u00e7o, os dados, como o nome pr\u00f3prio e o apelido, bem como o endere\u00e7o de e-mail, ser\u00e3o tratados. O fundamento jur\u00eddico \u00e9 o consentimento, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea a) do RGPD. Pode revogar o seu consentimento a qualquer momento. Este servi\u00e7o poder\u00e1 transferir dados para fora da UE\/EEE. Nesse caso, assin\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os, que est\u00e1 inclu\u00eddo na Lista do <a href=\"https:\/\/www.dataprivacyframework.gov\/list\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">Quadro de Privacidade dos Dados<\/a>. Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pela Google, pode consultar a <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidade<\/a> da Google.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Meta Custom Audiences<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos os P\u00fablicos personalizados da Meta para efeitos de marketing e ressegmenta\u00e7\u00e3o. Este servi\u00e7o \u00e9 fornecido pela Meta Platform Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbor, Dublin, D02, Irlanda. Ao utilizar este servi\u00e7o, os dados, como o nome pr\u00f3prio e o apelido, bem como endere\u00e7os de e-mail, poder\u00e3o ser tratados. O fundamento jur\u00eddico \u00e9 o consentimento, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea a) do RGPD. Pode revogar o seu consentimento a qualquer momento. Este servi\u00e7o poder\u00e1 transferir dados para fora da UE\/EEE. Nesse caso, assin\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os, que est\u00e1 inclu\u00eddo na Lista do <a href=\"https:\/\/www.dataprivacyframework.gov\/list\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">Quadro de Privacidade dos Dados<\/a>. Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pela Meta, pode consultar a <a href=\"https:\/\/www.facebook.com\/privacy\/explanation\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidade<\/a> da Meta.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>LinkedIn Matched Audiences<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o Matched Audiences do LinkedIn para efeitos de marketing e ressegmenta\u00e7\u00e3o. Este servi\u00e7o \u00e9 fornecido pela LinkedIn Ireland Unlimited Company, Wilton Place, Dublin 2, Irlanda. Ao utilizar este servi\u00e7o, os dados, como o nome pr\u00f3prio e o apelido, bem como endere\u00e7os de e-mail, poder\u00e3o ser tratados. O fundamento jur\u00eddico \u00e9 o consentimento, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea a) do RGPD. Pode revogar o seu consentimento a qualquer momento. Este servi\u00e7o poder\u00e1 transferir dados para fora da UE\/EEE. Nesse caso, assin\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os, que est\u00e1 inclu\u00eddo na Lista do <a href=\"https:\/\/www.dataprivacyframework.gov\/list\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">Quadro de Privacidade dos Dados<\/a>. Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pelo LinkedIn, pode consultar a <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"nofollow noreferrer noopener\">pol\u00edtica de privacidade<\/a> do LinkedIn.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Impact<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Utilizamos o servi\u00e7o fornecido pela Impact como servi\u00e7o de marketing afiliado. O servi\u00e7o \u00e9 fornecido pela Impact Tech, Inc., 223 E. De La Guerra Street, Santa Barbara, CA 93101, Estados Unidos da Am\u00e9rica. O fundamento jur\u00eddico \u00e9 o consentimento, art. 6.\u00ba, par\u00e1. 1, frase 1, al\u00ednea a) do RGPD. Pode revogar o seu consentimento a qualquer momento. Ao utilizar este servi\u00e7o, dados como o endere\u00e7o IP, informa\u00e7\u00f5es do browser, p\u00e1ginas visitadas, data e hora da visita, atividade do website, dados do utilizador e identificadores de cookies (irclickid e irpid) podem ser tratados. Este servi\u00e7o poder\u00e1 transferir dados para fora da UE\/EEE. Nesse caso, aceit\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os.<\/p>\n\n\n\n<p>Para obter mais informa\u00e7\u00f5es sobre como os dados s\u00e3o tratados pela Impact, pode consultar a <a href=\"https:\/\/impact.com\/privacy-policy\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">pol\u00edtica de privacidade<\/a> da Impact ou contactar a Impact atrav\u00e9s do endere\u00e7o <a href=\"mailto:privacy@impact.com\">privacy@impact.com<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>WP Engine<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Estamos a utilizar o servi\u00e7o fornecido pela WP Engine como servi\u00e7o de alojamento do nosso website. O servi\u00e7o \u00e9 prestado pela WPEngine, Inc., 504 Lavaca St #1000, Austin, TX 78701, Estados Unidos da Am\u00e9rica. A base legal \u00e9 o consentimento, nos termos do Art. 6.\u00ba, n.\u00ba 1, al\u00ednea f) do RGPD, uma vez que \u00e9 necess\u00e1rio para o funcionamento do website. Ao utilizar este servi\u00e7o, podem ser processados dados, como os mencionados na sec\u00e7\u00e3o IV. Este servi\u00e7o pode transferir dados para fora da UE\/EEE. Para esse efeito, assin\u00e1mos cl\u00e1usulas contratuais-tipo com o prestador de servi\u00e7os e este encontra-se inclu\u00eddo na lista <a href=\"https:\/\/www.dataprivacyframework.gov\/list\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Data Privacy Framework<\/a>.<\/p>\n\n\n\n<p>Para mais informa\u00e7\u00f5es sobre o tratamento de dados pela WP Engine, pode consultar a <a href=\"https:\/\/wpengine.com\/legal\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">pol\u00edtica de privacidade<\/a> da WP Engine ou contactar a WPEngine atrav\u00e9s do endere\u00e7o <a href=\"mailto:legal@wpengine.com\">legal@wpengine.com<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Vanta<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Estamos a utilizar o servi\u00e7o disponibilizado pela Vanta para alojar o Centro de Confian\u00e7a Usercentrics e a fun\u00e7\u00e3o de chat e pesquisa com IA. O servi\u00e7o \u00e9 assegurado pela Vanta Inc., 655 Montgomery Street S\u00e3o Francisco, CA 94111. A base legal para a utiliza\u00e7\u00e3o deste servi\u00e7o \u00e9 o interesse leg\u00edtimo, conforme o art.\u00ba 6.\u00ba, par\u00e1. 1, frase 1 al\u00ednea f do RGPD, uma vez que o servi\u00e7o \u00e9 necess\u00e1rio para fornecer acesso \u00e0 documenta\u00e7\u00e3o de seguran\u00e7a e privacidade da Usercentrics. Ao utilizar este servi\u00e7o, s\u00e3o processados dados como o endere\u00e7o IP, endere\u00e7o de e-mail, visualiza\u00e7\u00f5es de p\u00e1gina, visualiza\u00e7\u00f5es e downloads de recursos, reprodu\u00e7\u00f5es de v\u00eddeo e conversas com o chatbot. Nesse caso, assin\u00e1mos cl\u00e1usulas contratuais padr\u00e3o com o fornecedor do servi\u00e7o e o fornecedor est\u00e1 inclu\u00eddo na Data Privacy Framework List.<\/p>\n\n\n\n<p>Para mais informa\u00e7\u00f5es sobre a forma como os dados s\u00e3o tratados pela Vanta, pode consultar a <a href=\"https:\/\/www.vanta.com\/legal\/privacy\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">pol\u00edtica de privacidade da Vanta<\/a> ou contactar a Vanta atrav\u00e9s do endere\u00e7o <a href=\"mailto:privacy@vanta.com\">privacy@vanta.com<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Destinat\u00e1rios dos dados<\/h3>\n\n\n\n<p>A Usercentrics n\u00e3o vende, comercializa ou transfere de qualquer outra forma para terceiros quaisquer informa\u00e7\u00f5es pessoalmente identific\u00e1veis.<\/p>\n\n\n\n<p>Isto n\u00e3o inclui terceiros ou subcontratantes fi\u00e1veis que nos ajudam na opera\u00e7\u00e3o do nosso website, a realizar as nossas atividades comerciais ou a prestar-lhe assist\u00eancia. Essas entidades fi\u00e1veis podem ter acesso a informa\u00e7\u00f5es pessoalmente identific\u00e1veis com base na necessidade de as conhecerem e ser\u00e3o contratualmente obrigadas a manter a confidencialidade das suas informa\u00e7\u00f5es.<\/p>\n\n\n\n<p>Tamb\u00e9m partilharemos dados com as entidades Usercentrics (Usercentrics A\/S, Usercentrics GmbH, Cybot A\/S [incluindo a CYBOT A\/S, o escrit\u00f3rio da od\u0161t\u011bpn\u00fd z\u00e1vod em Praga]<br>, Usercentrics Unipessoal e Usercentrics Inc.), incluindo a partilha de dados entre os produtos Cookiebot\u2122 e Usercentrics, quando necess\u00e1rio. Todas as entidades podem ter acesso a informa\u00e7\u00f5es pessoalmente identific\u00e1veis com base na necessidade de as conhecerem e ser\u00e3o contratualmente obrigadas a manter as suas informa\u00e7\u00f5es confidenciais (acordo de respons\u00e1vel conjunto pelo tratamento de dados).<\/p>\n\n\n\n<p>Tamb\u00e9m poderemos divulgar as suas informa\u00e7\u00f5es quando considerarmos que a divulga\u00e7\u00e3o \u00e9 adequada para cumprir a lei, aplicar as pol\u00edticas do nosso site ou proteger os nossos direitos, propriedade ou seguran\u00e7a, ou os de terceiros. Al\u00e9m disso, podem ser fornecidas a outras entidades informa\u00e7\u00f5es n\u00e3o pessoalmente identific\u00e1veis de visitantes para fins de marketing, publicidade ou outras utiliza\u00e7\u00f5es.<\/p>\n\n\n\n<p>Apenas transmitimos os dados que recolhemos se tal for necess\u00e1rio para o cumprimento do contrato ou para o fornecimento da funcionalidade t\u00e9cnica do website, ou se existir outro fundamento jur\u00eddico para a transmiss\u00e3o dos dados.<\/p>\n\n\n\n<p>Em princ\u00edpio, seremos n\u00f3s a tratar os seus dados. No entanto, em alguns casos, tamb\u00e9m utilizamos prestadores de servi\u00e7os. Al\u00e9m dos subcontratantes mencionados nesta pol\u00edtica de privacidade, estes podem incluir, em particular, centros de dados que armazenam os nossos websites e bases de dados, prestadores de servi\u00e7os de TI que mant\u00eam os nossos sistemas e empresas de consultoria. Se transmitirmos dados a subcontratantes, estes apenas poder\u00e3o utilizar os dados para cumprir as respetivas tarefas. Os subcontratantes foram cuidadosamente selecionados e contratados por n\u00f3s. Est\u00e3o contratualmente vinculados \u00e0s nossas instru\u00e7\u00f5es, t\u00eam medidas t\u00e9cnicas e organizacionais adequadas para proteger os direitos dos titulares dos dados e s\u00e3o regularmente monitorizados por n\u00f3s.<\/p>\n\n\n\n<p>Al\u00e9m disso, a divulga\u00e7\u00e3o pode ocorrer em rela\u00e7\u00e3o a inqu\u00e9ritos oficiais, ordens judiciais e processos judiciais, se tal for necess\u00e1rio para a a\u00e7\u00e3o judicial ou a aplica\u00e7\u00e3o da lei. Quando os governos realizam um pedido l\u00edcito de dados de clientes da Usercentrics, a Usercentrics esfor\u00e7a-se por limitar a divulga\u00e7\u00e3o. A Usercentrics apenas divulgar\u00e1 os dados espec\u00edficos exigidos pelo pedido l\u00edcito relevante.<\/p>\n\n\n\n<p>Se for obrigada a divulgar os seus dados, a Usercentrics ir\u00e1 notific\u00e1-lo de imediato e fornecer-lhe uma c\u00f3pia do pedido, salvo se legalmente proibida de o fazer.<\/p>\n\n\n\n<p>Se a Usercentrics delegar a terceiros a recolha, o tratamento e a utiliza\u00e7\u00e3o de dados no \u00e2mbito do tratamento contratado, em conformidade com o artigo 28.\u00ba do RGPD, esta delega\u00e7\u00e3o tamb\u00e9m ocorrer\u00e1 exclusivamente em conformidade com as disposi\u00e7\u00f5es legais relativas \u00e0 prote\u00e7\u00e3o de dados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-matomo-opt-out\">Matomo Opt-Out<\/h3>\n\n\n\n<iframe style=\"border: 0; height: 200px; width: 600px;\" src=\"https:\/\/analytics.usercentrics.com\/index.php?module=CoreAdminHome&amp;action=optOut&amp;language=pt\" title=\"Matomo Opt-Out\"><\/iframe>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-10\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-10-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-10-content\">\n        X. CONFORMIDADE COM A LEI DE PRIVACIDADE DO CONSUMIDOR DA CALIF\u00d3RNIA (CCPA)    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-10-content\"\n         aria-labelledby=\"uc-accordion-item-10-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<p>Al\u00e9m das disposi\u00e7\u00f5es acima mencionadas, as seguintes aplicam-se especificamente aos residentes na Calif\u00f3rnia, EUA.<\/p>\n\n\n\n<p>As leis de privacidade da Calif\u00f3rnia garantem aos seus residentes direitos espec\u00edficos sobre suas informa\u00e7\u00f5es pessoais. Esta sec\u00e7\u00e3o descreve os direitos dos consumidores e explica como exercer esses direitos, os quais est\u00e3o sujeitos \u00e0s excep\u00e7\u00f5es ao abrigo da lei.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Os seus direitos sob a Lei de Privacidade da Calif\u00f3rnia<\/li>\n<\/ol>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Direito de saber sobre as informa\u00e7\u00f5es pessoais recolhidas, vendidas ou compartilhadas (&#8220;Direito de saber&#8221;)<\/li>\n<\/ul>\n\n\n\n<p>Tem o direito de solicitar as informa\u00e7\u00f5es pessoais que recolhemos sobre si, incluindo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>As categorias de informa\u00e7\u00f5es pessoais recolhidas<\/li>\n\n\n\n<li>As categorias de fontes das quais as informa\u00e7\u00f5es pessoais s\u00e3o recolhidas,<\/li>\n\n\n\n<li>A finalidade comercial ou de neg\u00f3cios da recolha ou venda de informa\u00e7\u00f5es pessoais<\/li>\n\n\n\n<li>As categorias de terceiros para as quais as informa\u00e7\u00f5es pessoais s\u00e3o compartilhadas<\/li>\n\n\n\n<li>As informa\u00e7\u00f5es pessoais espec\u00edficas recolhidas sobre voc\u00ea que s\u00e3o permitidas por lei<\/li>\n\n\n\n<li>Direito de solicitar a elimina\u00e7\u00e3o de informa\u00e7\u00f5es pessoais (&#8220;Direito de eliminar&#8221;)<\/li>\n<\/ul>\n\n\n\n<p>Tem o direito de solicitar a elimina\u00e7\u00e3o de qualquer uma das suas informa\u00e7\u00f5es pessoais recolhidas por n\u00f3s, que est\u00e1 sujeita a determinadas exce\u00e7\u00f5es. Assim que recebermos a sua solicita\u00e7\u00e3o <b>e verificarmos a sua identidade<\/b>, eliminaremos (e orientaremos os nossos prestadores de servi\u00e7os a eliminar) as suas informa\u00e7\u00f5es pessoais dos nossos registos, a menos que uma exce\u00e7\u00e3o seja aplic\u00e1vel.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Direito de corrigir informa\u00e7\u00f5es pessoais imprecisas (&#8220;Direito de corrigir&#8221;)<\/li>\n<\/ul>\n\n\n\n<p>Tem o direito de solicitar a corre\u00e7\u00e3o de informa\u00e7\u00f5es pessoais imprecisas que mantemos sobre si ou atualizar as informa\u00e7\u00f5es arquivadas por n\u00f3s.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Direito de impedir a venda ou a partilha das suas informa\u00e7\u00f5es pessoais<\/li>\n<\/ul>\n\n\n\n<p>Tem o direito de impedir a venda ou a partilha de informa\u00e7\u00f5es pessoais. A Usercentrics n\u00e3o vende informa\u00e7\u00f5es pessoais, incluindo informa\u00e7\u00f5es pessoais de menores de 16 anos. Pode utilizar o seu direito de impedir a venda ou a partilha de informa\u00e7\u00f5es pessoais clicando no link &#8220;N\u00e3o vender ou partilhar minhas informa\u00e7\u00f5es pessoais&#8221; no final da p\u00e1gina.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Direito a n\u00e3o sofrer discrimina\u00e7\u00e3o pelo exerc\u00edcio dos seus direitos de privacidade<\/li>\n<\/ul>\n\n\n\n<p>Tem o direito de estar protegido(a) contra a discrimina\u00e7\u00e3o por exercer os seus direitos. N\u00e3o o discriminaremos por exercer os seus direitos.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Direito de limitar o uso de informa\u00e7\u00f5es pessoais confidenciais<\/li>\n<\/ul>\n\n\n\n<p>A Usercentrics n\u00e3o usa informa\u00e7\u00f5es pessoais confidenciais de nenhuma maneira que exija o recurso a um direito para limitar o seu uso.<\/p>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>Como enviar uma solicita\u00e7\u00e3o para exercer seu direito de saber, eliminar ou corrigir<\/li>\n<\/ol>\n\n\n\n<p>Pode enviar a sua solicita\u00e7\u00e3o atrav\u00e9s de e-mail para <a href=\"mailto:privacy@usercentrics.com\">privacy@usercentrics.com<\/a>. Compararemos as informa\u00e7\u00f5es que nos enviar com as informa\u00e7\u00f5es que temos nos nossos registos para garantir que sua solicita\u00e7\u00e3o atenda \u00e0 defini\u00e7\u00e3o de &#8220;solicita\u00e7\u00e3o de consumidor verific\u00e1vel&#8221; de acordo com as Leis de privacidade da Calif\u00f3rnia. Responderemos \u00e0 sua solicita\u00e7\u00e3o de acordo com as exig\u00eancias.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><br><h4><b>Tempo e formato da resposta<\/b><\/h4><br><\/li>\n<\/ul>\n\n\n\n<p>A Usercentrics esfor\u00e7a-se para responder a uma solicita\u00e7\u00e3o dentro de quarenta e cinco (45) dias ap\u00f3s a recep\u00e7\u00e3o. Se a Usercentrics precisar de mais tempo (at\u00e9 90 dias), ser\u00e1 informado(a) do motivo e do per\u00edodo de extens\u00e3o por escrito. Qualquer divulga\u00e7\u00e3o fornecida cobrir\u00e1 apenas o per\u00edodo de doze (12) meses anterior \u00e0 recep\u00e7\u00e3o da solicita\u00e7\u00e3o verific\u00e1vel. Se aplic\u00e1vel, a resposta tamb\u00e9m explicar\u00e1 os motivos pelos quais a Usercentrics n\u00e3o pode atender \u00e0 solicita\u00e7\u00e3o. Para solicita\u00e7\u00f5es de portabilidade de dados, a Usercentrics selecionar\u00e1 um formato para fornecer as informa\u00e7\u00f5es pessoais que est\u00e3o prontas para uso, permitindo que a transmiss\u00e3o das informa\u00e7\u00f5es de uma entidade para outra ocorra sem obst\u00e1culos. A Usercentrics n\u00e3o cobra uma taxa para processar ou responder \u00e0 solicita\u00e7\u00e3o verific\u00e1vel, a menos que ela seja excessiva, repetitiva ou claramente infundada. Se a Usercentrics determinar que a solicita\u00e7\u00e3o justifica uma taxa, informaremos como essa decis\u00e3o foi tomada e ofereceremos uma estimativa de custo antes de conclu\u00ed-la.<\/p>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>Crian\u00e7as menores de 16 anos<\/li>\n<\/ol>\n\n\n\n<p>A Usercentrics n\u00e3o recolhe nem divulga de forma intencional as informa\u00e7\u00f5es pessoais de crian\u00e7as menores de 16 anos de idade. Conforme mencionado acima, a Usercentrics tamb\u00e9m n\u00e3o vende nem partilha informa\u00e7\u00f5es pessoais de crian\u00e7as menores de 16 anos de idade.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-11\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-11-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-11-content\">\n        XI. MENORES DE IDADE    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-11-content\"\n         aria-labelledby=\"uc-accordion-item-11-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<p>Os nossos servi\u00e7os n\u00e3o s\u00e3o destinados a crian\u00e7as menores de 13 anos. N\u00e3o recolhemos dados de crian\u00e7as menores de 13 anos conscientemente. Se n\u00e3o tiver alcan\u00e7ado esta idade, n\u00e3o utilize os servi\u00e7os e n\u00e3o nos forne\u00e7a os seus dados pessoais. Se for pai de uma crian\u00e7a abaixo deste limite de idade e tiver conhecimento de que seu filho transmitiu dados pessoais \u00e0 Usercentrics, por favor entre em contato conosco em <a href=\"mailto:datenschutz@usercentrics.com\">datenschutz@usercentrics.com<\/a> e requisite o exerc\u00edcio de seus direitos de acesso, corre\u00e7\u00e3o, dele\u00e7\u00e3o e\/ou revoga\u00e7\u00e3o. Se for residente da Calif\u00f3rnia e ainda n\u00e3o tiver 18 anos de idade e quiser eliminar conte\u00fados acess\u00edveis ao p\u00fablico, entre em contato conosco em <a href=\"mailto:datenschutz@usercentrics.com\">datenschutz@usercentrics.com<\/a>.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-12\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-12-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-12-content\">\n        XII. PRESEN\u00c7A ONLINE EM REDES SOCIAIS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-12-content\"\n         aria-labelledby=\"uc-accordion-item-12-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<p>Mantemos presen\u00e7as online em redes sociais para comunicarmos com clientes e partes interessadas, entre outros, e para fornecer informa\u00e7\u00f5es sobre os nossos produtos e servi\u00e7os.<\/p>\n\n\n\n<p>Os dados dos utilizadores s\u00e3o normalmente processados pelas redes sociais em causa para fins de investiga\u00e7\u00e3o de mercado e publicidade. Dessa forma, os perfis de uso podem ser criados com base nos interesses dos utilizadores. Para isso, cookies e outros identificadores s\u00e3o armazenados nos computadores dos utilizadores. Com base nesses perfis de uso, an\u00fancios, por exemplo, s\u00e3o colocados nas redes sociais, mas tamb\u00e9m em sites de terceiros.<\/p>\n\n\n\n<p>Como parte da opera\u00e7\u00e3o das nossas presen\u00e7as online, \u00e9 poss\u00edvel que possamos acessar informa\u00e7\u00f5es como estat\u00edsticas sobre o uso de nossas presen\u00e7as online, que s\u00e3o fornecidas pelas redes sociais. Essas estat\u00edsticas s\u00e3o agregadas e podem incluir, em particular, informa\u00e7\u00f5es demogr\u00e1ficas e dados sobre intera\u00e7\u00e3o com nossas presen\u00e7as online e publica\u00e7\u00f5es e conte\u00fado distribu\u00eddos por elas. Consulte a lista abaixo para obter detalhes e links para os dados das redes sociais que podemos acessar como operadores das presen\u00e7as online.<\/p>\n\n\n\n<p>A base legal para o processamento de dados \u00e9 art. 6, al\u00ednea 1, s. 1, letra a e b do RGPD, a fim de manter contato com os nossos clientes, inform\u00e1-los, e realizar medidas pr\u00e9-contratuais com futuros clientes e partes interessadas.<\/p>\n\n\n\n<p>Para obter a base jur\u00eddica do processamento de dados efetuado pelas redes sociais sob sua pr\u00f3pria responsabilidade, consulte as informa\u00e7\u00f5es sobre prote\u00e7\u00e3o de dados da respetiva rede social. Os links abaixo tamb\u00e9m fornecem mais informa\u00e7\u00f5es sobre o respectivo processamento de dados e as op\u00e7\u00f5es de oposi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Gostar\u00edamos de salientar que os pedidos de prote\u00e7\u00e3o de dados podem ser mais eficazes com o respetivo fornecedor da rede social, uma vez que apenas estes fornecedores t\u00eam acesso aos dados e podem tomar medidas adequadas diretamente. Veja abaixo uma lista com informa\u00e7\u00f5es sobre as redes sociais nas quais operamos presen\u00e7as online:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Facebook (EUA e Canad\u00e1: Facebook Inc., 1601 Willow Road, Menlo Park, Calif\u00f3rnia 94025, EUA; todos os outros pa\u00edses: Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbor, Dublin 2, Irlanda).\n<ul class=\"wp-block-list\">\n<li>Opera\u00e7\u00e3o do Fanpage do Facebook em responsabilidade conjunta com base em um acordo sobre o processamento conjunto de dados pessoais (chamado Suplemento de Percep\u00e7\u00f5es de P\u00e1gina sobre o controlador).<\/li>\n\n\n\n<li>Informa\u00e7\u00f5es sobre os dados processados do Page Insights e a op\u00e7\u00e3o de contato no caso de consultas de prote\u00e7\u00e3o de dados: <a href=\"https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data<\/a><\/li>\n\n\n\n<li>Pol\u00edtica de privacidade: <a href=\"https:\/\/www.facebook.com\/privacy\/policy\/?entry_point=data_policy_redirect&amp;entry=0\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/about\/privacy\/<\/a><\/li>\n\n\n\n<li>Opt-out: <a href=\"https:\/\/www.facebook.com\/login.php?next=https%3A%2F%2Fwww.facebook.com%2Fsettings%3Ftab%3Dads\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/settings?tab=ads e http:\/\/www.youronlinechoices.com<\/a>.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Instagram (Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbor, Dublin 2, Irlanda).\n<ul class=\"wp-block-list\">\n<li>Pol\u00edtica de privacidade: <a href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\" rel=\"noopener\">https:\/\/help.instagram.com\/519522125107875<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Google\/YouTube (Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlanda).\n<ul class=\"wp-block-list\">\n<li>Pol\u00edtica de privacidade: <a href=\"https:\/\/policies.google.com\/privacy?hl=en\" target=\"_blank\" rel=\"noopener\">https:\/\/policies.google.com\/privacy?hl=en<\/a><\/li>\n\n\n\n<li>Opt-out: <a href=\"https:\/\/www.google.com\/settings\/ads\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/settings\/ads<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Twitter (Twitter International Company, One Cumberland Place, Fenian Street, Dublin 2, D02 AX07 Irlanda).\n<ul class=\"wp-block-list\">\n<li>Pol\u00edtica de privacidade: <a href=\"https:\/\/twitter.com\/en\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/twitter.com\/en\/privacy<\/a><\/li>\n\n\n\n<li>Opt-out:<a href=\"https:\/\/twitter.com\/personalization\" target=\"_blank\" rel=\"noopener\"> https:\/\/twitter.com\/personalization<\/a>.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>LinkedIn (LinkedIn Ireland Unlimited Company Wilton Place, Dublin 2, Irlanda).\n<ul class=\"wp-block-list\">\n<li>Opera\u00e7\u00e3o da p\u00e1gina da empresa do LinkedIn em responsabilidade conjunta com base em um acordo sobre o processamento conjunto de dados pessoais (chamado Adendo ao Controlador conjunto de percep\u00e7\u00f5es de P\u00e1gina).<\/li>\n\n\n\n<li>Informa\u00e7\u00f5es sobre os dados do Page Insights processados e a op\u00e7\u00e3o de contato no caso de consultas de prote\u00e7\u00e3o de dados: <a href=\"https:\/\/legal.linkedin.com\/pages-joint-controller-addendum\" target=\"_blank\" rel=\"noopener\">https:\/\/legal.linkedin.com\/pages-joint-controller-addendum<\/a><\/li>\n\n\n\n<li>Pol\u00edtica de privacidade: <a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a><\/li>\n\n\n\n<li>Opt-out: <a href=\"https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out<\/a>.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Google my business\n<ul class=\"wp-block-list\">\n<li>Operamos uma entrada chamada Google My Business. Caso nos encontre desta forma, utilizamos o servi\u00e7o de informa\u00e7\u00e3o oferecido pela Google e os servi\u00e7os da Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlanda (doravante &#8220;Google&#8221;).<\/li>\n\n\n\n<li>Gostar\u00edamos de destacar que usa o site da Google e as suas fun\u00e7\u00f5es sob sua pr\u00f3pria responsabilidade. Tal aplica-se principalmente ao uso das fun\u00e7\u00f5es sociais e interativas (por exemplo, coment\u00e1rios, partilha, classifica\u00e7\u00e3o, mensagens diretas). Quando visita e interage com a nossa entrada no Google My Business, a Google tamb\u00e9m recolhe o seu endere\u00e7o IP e outras informa\u00e7\u00f5es presentes no seu dispositivo de terminal na forma dos chamados cookies. Essas informa\u00e7\u00f5es s\u00e3o usadas para nos fornecer, como operador da entrada do Google My Business, informa\u00e7\u00f5es estat\u00edsticas sobre o uso dos servi\u00e7os da Google. Os dados recolhidos sobre si neste contexto ser\u00e3o processados pela Google e poder\u00e3o ser transferidos para pa\u00edses fora da Uni\u00e3o Europeia. A Google geralmente descreve que informa\u00e7\u00f5es recebe e como s\u00e3o usadas na sua pol\u00edtica de privacidade. A Google fornece informa\u00e7\u00f5es mais detalhadas na sua pol\u00edtica de privacidade:<\/li>\n\n\n\n<li><a href=\"https:\/\/policies.google.com\/privacy?hl=pt\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de privacidade do Google<\/a><\/li>\n\n\n\n<li>N\u00e3o sabemos como a Google usa os dados da visita para seus pr\u00f3prios fins, at\u00e9 que ponto as atividades de utilizadores individuais s\u00e3o atribu\u00eddas, por quanto tempo o Google armazena esses dados e se os dados s\u00e3o transmitidos a terceiros. Ao acessar os servi\u00e7os da Google, o endere\u00e7o IP atribu\u00eddo ao seu dispositivo de terminal \u00e9 transmitido para a Google. A Google tamb\u00e9m armazena informa\u00e7\u00f5es sobre os dispositivos finais dos seus utilizadores, o que pode permitir que a Google atribua endere\u00e7os IP a utilizadores individuais ou contas de utilizador.<\/li>\n\n\n\n<li>Se entrar em contato conosco por meio da nossa entrada do Google My Business ou outros servi\u00e7os da Google por mensagem direta, n\u00e3o poderemos excluir a possibilidade de que essas mensagens tamb\u00e9m sejam lidas e avaliadas pela Google (tanto por funcion\u00e1rios quanto automaticamente). Portanto, aconselhamos a n\u00e3o nos fornecer dados pessoais por essa via. Em vez disso, outra forma de comunica\u00e7\u00e3o deve ser escolhida o mais cedo poss\u00edvel. Exclu\u00edmos conversas at\u00e9 14 dias ap\u00f3s a \u00faltima atividade de chat ou imediatamente ap\u00f3s a troca para outro canal de comunica\u00e7\u00e3o. O uso deste servi\u00e7o est\u00e1 sujeito \u00e0 Pol\u00edtica de Privacidade da Google, com a qual &#8211; com uso &#8211; j\u00e1 concordou.<\/li>\n\n\n\n<li>Enquanto provedor de nossa entrada do Google My Business, n\u00e3o recolhemos nem processamos nenhum dado adicional do seu uso deste servi\u00e7o da Google. Al\u00e9m disso, n\u00e3o usamos nenhuma fun\u00e7\u00e3o da Google no nosso site.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-13\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-13-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-13-content\">\n        XIII. TRANSFER\u00caNCIA DE DADOS PARA PA\u00cdSES TERCEIROS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-13-content\"\n         aria-labelledby=\"uc-accordion-item-13-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<p>Tal como explicado nesta pol\u00edtica de privacidade, utilizamos servi\u00e7os cujos prestadores est\u00e3o parcialmente localizados nos chamados pa\u00edses terceiros (fora da Uni\u00e3o Europeia ou do espa\u00e7o Econ\u00f3mico Europeu) ou processamos dados pessoais nesses pa\u00edses, ou seja, pa\u00edses cujo n\u00edvel de prote\u00e7\u00e3o de dados n\u00e3o corresponde ao da Uni\u00e3o Europeia. Quando for esse o caso e a Comiss\u00e3o Europeia n\u00e3o tiver emitido uma decis\u00e3o de adequa\u00e7\u00e3o (Art 45 RGPD) para esses pa\u00edses, tom\u00e1mos as devidas precau\u00e7\u00f5es para garantir um n\u00edvel adequado de prote\u00e7\u00e3o de dados para qualquer transfer\u00eancia de dados, de acordo com o Art. 44 et seq. do RGPD. Estas incluem, entre outras, as cl\u00e1usulas contratuais padronizadas da Uni\u00e3o Europeia ou regulamentos internos vinculativos em mat\u00e9ria de prote\u00e7\u00e3o de dados.<\/p>\n\n\n\n<p>Se uma transfer\u00eancia para um pa\u00eds terceiro for prevista e n\u00e3o houver decis\u00e3o de adequa\u00e7\u00e3o ou medidas de seguran\u00e7a adequadas, \u00e9 poss\u00edvel e existe o risco de que as autoridades no respetivo pa\u00eds terceiro (por exemplo, servi\u00e7os de intelig\u00eancia) possam obter acesso aos dados transferidos para que possam recolh\u00ea-los e analis\u00e1-los, e que a aplicabilidade de seus direitos de titulares de dados n\u00e3o pode ser garantida.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-14\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-14-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-14-content\">\n        XIV. LINKS DE TERCEIROS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-14-content\"\n         aria-labelledby=\"uc-accordion-item-14-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<p>Ocasionalmente e a nosso crit\u00e9rio, podemos incluir ou oferecer produtos ou servi\u00e7os de terceiros no nosso site. Esses sites de terceiros t\u00eam pol\u00edticas de privacidade independentes e separadas. Portanto, n\u00e3o nos responsabilizamos pelo conte\u00fado e pelas atividades desses sites vinculados. No entanto, procuramos proteger a integridade de nosso site e aceitamos receber qualquer feedback sobre os mesmos.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-15\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-15-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-15-content\">\n        XV. OS SEUS DIREITOS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-15-content\"\n         aria-labelledby=\"uc-accordion-item-15-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<p>Se processarmos os seus dados pessoais, tem &#8211; ap\u00f3s identifica\u00e7\u00e3o bem sucedida &#8211; os seguintes direitos em rela\u00e7\u00e3o a n\u00f3s:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Direito \u00e0 informa\u00e7\u00e3o (Artigo 15 RGPD, par\u00e1grafo 34, BDSG)<\/li>\n\n\n\n<li>Direito de elimina\u00e7\u00e3o (Artigo 17 RGPD, par\u00e1grafo 35 BDSG)<\/li>\n\n\n\n<li>Direito de retifica\u00e7\u00e3o (Artigo 16 RGPD, Se\u00e7\u00e3o 34 BDSG)<\/li>\n\n\n\n<li>Direito \u00e0 restri\u00e7\u00e3o de processamento (Artigo 18 RGPD)<\/li>\n\n\n\n<li>Direito \u00e0 portabilidade de dados (Artigo 20 RGPD)<\/li>\n\n\n\n<li>Direito de revogar o consentimento (Artigo 7(3) RGPD)<\/li>\n\n\n\n<li>Direito de se opor a determinadas atividades de processamento de dados (Artigo 21 RGPD).<\/li>\n<\/ul>\n\n\n\n<p>Para exercer os seus direitos aqui descritos, pode apresentar o seu pedido atrav\u00e9s <a href=\"https:\/\/usercentrics.privacy.saymine.io\/Usercentrics?iframe=true\">deste formul\u00e1rio<\/a>.<\/p>\n\n\n\n<p>Tem tamb\u00e9m o direito de reclamar junto da autoridade de supervis\u00e3o de prote\u00e7\u00e3o de dados respons\u00e1vel. Pode entrar em contato com a autoridade de prote\u00e7\u00e3o de dados do seu local de resid\u00eancia, que encaminhar\u00e1 a sua solicita\u00e7\u00e3o \u00e0 autoridade competente.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-16\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-16-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-16-content\">\n        XVI. SEGURAN\u00c7A E INTEGRIDADE DOS DADOS    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-16-content\"\n         aria-labelledby=\"uc-accordion-item-16-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<p>A prote\u00e7\u00e3o dos dados que nos forneceu ou que obtivemos sobre si tem prioridade para n\u00f3s. Tomamos medidas adequadas de seguran\u00e7a para proteger os seus dados de perda, mau uso e acesso, altera\u00e7\u00e3o, divulga\u00e7\u00e3o ou destrui\u00e7\u00e3o n\u00e3o autorizados. A Usercentrics tomou medidas para garantir a confidencialidade, integridade, disponibilidade e resili\u00eancia de sistemas e servi\u00e7os que processam dados pessoais e recuperar\u00e1 a disponibilidade e o acesso das informa\u00e7\u00f5es em caso de ocorr\u00eancia f\u00edsica ou t\u00e9cnica em tempo \u00fatil.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"uc-accordion-item\" id=\"uc-accordion-item-17\">\n    <h3 class=\"uc-accordion-item__title no-default-margin\">    <button class=\"uc-accordion-item__button\"\n            id=\"uc-accordion-item-17-button\"\n            aria-expanded=\"false\"\n            aria-controls=\"uc-accordion-item-17-content\">\n        XVII. ATUALIZA\u00c7\u00d5ES    <\/button>\n    <\/h3>    <div class=\"uc-accordion-item__content\"\n         id=\"uc-accordion-item-17-content\"\n         aria-labelledby=\"uc-accordion-item-17-button\">\n        <div class=\"uc-accordion-item__content__inner\">\n            \n\n<p>N\u00f3s nos reservamos o direito de atualizar esta Pol\u00edtica de Privacidade de tempos a tempos. Caso fa\u00e7amos altera\u00e7\u00f5es substanciais que restrinjam os seus direitos ou as obriga\u00e7\u00f5es da Usercentrics no \u00e2mbito desta Pol\u00edtica de Privacidade, n\u00f3s publicaremos nesta se\u00e7\u00e3o da declara\u00e7\u00e3o de prote\u00e7\u00e3o de dados uma instru\u00e7\u00e3o clara que informa os utilizadores quando esta for atualizada.<\/p>\n\n        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<p>Clicar <a href=\"\/pt\/privacy-policy-valid-until-november-11-2025\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">aqui<\/a> para ver a Pol\u00edtica de Privacidade v\u00e1lida at\u00e9 11 de novembro de 2025.<\/p>\n\n<\/div>\n\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"editor_notices":[],"footnotes":""},"class_list":["post-7324","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<title>Declara\u00e7\u00e3o de Prote\u00e7\u00e3o de Dados da Usercentrics<\/title>\n<meta name=\"description\" content=\"Na Declara\u00e7\u00e3o de Prote\u00e7\u00e3o de Dados da Usercentrics, voc\u00ea encontra todas as informa\u00e7\u00f5es necess\u00e1rias sobre dados coletados e processados, bem como todas as tecnologias que usamos neste site.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Declara\u00e7\u00e3o de prote\u00e7\u00e3o de dados v\u00e1lida at\u00e9 15 de mar\u00e7o de 2026\" \/>\n<meta property=\"og:description\" content=\"Na Declara\u00e7\u00e3o de Prote\u00e7\u00e3o de Dados da Usercentrics, voc\u00ea encontra todas as informa\u00e7\u00f5es necess\u00e1rias sobre dados coletados e processados, bem como todas as tecnologias que usamos neste site.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/usercentrics.com\/pt\/privacy-policy-valid-until-march-15-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Consent Management Platform (CMP) Usercentrics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/usercentrics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T12:12:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/usercentrics.com\/pt\/wp-content\/uploads\/sites\/3\/2024\/09\/Asset-93-100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@usercentrics\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"49 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/usercentrics.com\\\/pt\\\/privacy-policy-valid-until-march-15-2026\\\/\",\"url\":\"https:\\\/\\\/usercentrics.com\\\/pt\\\/privacy-policy-valid-until-march-15-2026\\\/\",\"name\":\"Declara\u00e7\u00e3o de Prote\u00e7\u00e3o de Dados da Usercentrics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/usercentrics.com\\\/pt\\\/#website\"},\"datePublished\":\"2026-03-20T11:55:03+00:00\",\"dateModified\":\"2026-03-20T12:12:24+00:00\",\"description\":\"Na Declara\u00e7\u00e3o de Prote\u00e7\u00e3o de Dados da Usercentrics, voc\u00ea encontra todas as informa\u00e7\u00f5es necess\u00e1rias sobre dados coletados e processados, bem como todas as tecnologias que usamos neste site.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":\"https:\\\/\\\/usercentrics.com\\\/pt\\\/privacy-policy-valid-until-march-15-2026\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/usercentrics.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/usercentrics.com\\\/pt\\\/\",\"name\":\"Consent Management Platform (CMP) Usercentrics\",\"description\":\"Consent Management Platform (CMP) Usercentrics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/usercentrics.com\\\/pt\\\/?s={search_term_string}\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>","yoast_head_json":{"title":"Declara\u00e7\u00e3o de Prote\u00e7\u00e3o de Dados da Usercentrics","description":"Na Declara\u00e7\u00e3o de Prote\u00e7\u00e3o de Dados da Usercentrics, voc\u00ea encontra todas as informa\u00e7\u00f5es necess\u00e1rias sobre dados coletados e processados, bem como todas as tecnologias que usamos neste site.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"pt_BR","og_type":"article","og_title":"Declara\u00e7\u00e3o de prote\u00e7\u00e3o de dados v\u00e1lida at\u00e9 15 de mar\u00e7o de 2026","og_description":"Na Declara\u00e7\u00e3o de Prote\u00e7\u00e3o de Dados da Usercentrics, voc\u00ea encontra todas as informa\u00e7\u00f5es necess\u00e1rias sobre dados coletados e processados, bem como todas as tecnologias que usamos neste site.","og_url":"https:\/\/usercentrics.com\/pt\/privacy-policy-valid-until-march-15-2026\/","og_site_name":"Consent Management Platform (CMP) Usercentrics","article_publisher":"https:\/\/www.facebook.com\/usercentrics","article_modified_time":"2026-03-20T12:12:24+00:00","og_image":[{"width":1201,"height":631,"url":"https:\/\/usercentrics.com\/pt\/wp-content\/uploads\/sites\/3\/2024\/09\/Asset-93-100.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@usercentrics","twitter_misc":{"Est. reading time":"49 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/usercentrics.com\/pt\/privacy-policy-valid-until-march-15-2026\/","url":"https:\/\/usercentrics.com\/pt\/privacy-policy-valid-until-march-15-2026\/","name":"Declara\u00e7\u00e3o de Prote\u00e7\u00e3o de Dados da Usercentrics","isPartOf":{"@id":"https:\/\/usercentrics.com\/pt\/#website"},"datePublished":"2026-03-20T11:55:03+00:00","dateModified":"2026-03-20T12:12:24+00:00","description":"Na Declara\u00e7\u00e3o de Prote\u00e7\u00e3o de Dados da Usercentrics, voc\u00ea encontra todas as informa\u00e7\u00f5es necess\u00e1rias sobre dados coletados e processados, bem como todas as tecnologias que usamos neste site.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":"https:\/\/usercentrics.com\/pt\/privacy-policy-valid-until-march-15-2026\/"}]},{"@type":"WebSite","@id":"https:\/\/usercentrics.com\/pt\/#website","url":"https:\/\/usercentrics.com\/pt\/","name":"Consent Management Platform (CMP) Usercentrics","description":"Consent Management Platform (CMP) Usercentrics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/usercentrics.com\/pt\/?s={search_term_string}"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/usercentrics.com\/pt\/wp-json\/wp\/v2\/pages\/7324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usercentrics.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/usercentrics.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/usercentrics.com\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/usercentrics.com\/pt\/wp-json\/wp\/v2\/comments?post=7324"}],"version-history":[{"count":0,"href":"https:\/\/usercentrics.com\/pt\/wp-json\/wp\/v2\/pages\/7324\/revisions"}],"wp:attachment":[{"href":"https:\/\/usercentrics.com\/pt\/wp-json\/wp\/v2\/media?parent=7324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}